{"id":24599,"date":"2025-07-04T06:00:59","date_gmt":"2025-07-04T06:00:59","guid":{"rendered":"https:\/\/azud.com\/productos\/medidores\/"},"modified":"2026-07-03T05:18:47","modified_gmt":"2026-07-03T05:18:47","slug":"medidores","status":"publish","type":"productos","link":"https:\/\/azud.com\/pt-pt\/productos\/medidores\/","title":{"rendered":"AZUD META"},"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"nombre":"AZUD META","descripcion":"Contadores do tipo Woltman e multijacto  para medir e registar o volume e o caudal de \u00e1gua. <br \/>\r\nPodem detetar varia\u00e7\u00f5es de caudal causadas por falhas ou fugas na instala\u00e7\u00e3o ou obstru\u00e7\u00f5es nos gotejadores.","fotos":["https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/AZUD_META_tarifa-2.webp","https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/gama_AZUD_META_WT-1.webp","https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/gama_AZUD_META_MJ-2.webp"],"video_producto":"","referencia_de_producto":"18Z5","identificador_unico":"18Z5pt","productos_relacionados":"18Z2,17Z6,70Z1","etiqueta-producto":["contadores"],"caracteristicas_tecnicas":"Woltman, Multi-Jet<br \/>\r\nCertifica\u00e7\u00e3o MID e ME\u00d1E<br \/>\r\nMetal e pl\u00e1stico<br \/>\r\nPN10 e PN16","ideal_para":"","destacado":"Woltman, Multi-Jet<br \/>\r\nCertifica\u00e7\u00e3o MID e ME\u00d1E<br \/>\r\nMetal e pl\u00e1stico<br \/>\r\nPN10 e PN16","valores_diferenciales":[{"icono":"https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/icono_Fiabilidad_02-3.webp","titulo":"Confiabilidade","contenido":"<p>Validados em banco de ensaio com certifica\u00e7\u00e3o europeia MID (\u00e1gua pot\u00e1vel e rega) e certifica\u00e7\u00e3o espanhola ME\u00d1E (agricultura e ind\u00fastria)<\/p>"},{"icono":"https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/icono_Durabilidad_02-3.webp","titulo":"Durabilidade","contenido":"<p>Concebidos para resistir a condi\u00e7\u00f5es exigentes, sem comprometer o funcionamento a longo prazo<\/p>"},{"icono":"https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/icono_Precision_02-2.webp","titulo":"Precis\u00e3o","contenido":"<p>Medi\u00e7\u00e3o precisa desde caudais muito baixos, sem necessidade de tro\u00e7os retos a montante ou a jusante<\/p>"}],"apps":"","hoja_tecnica_1_url":"http:\/\/d7rh5s3nxmpy4.cloudfront.net\/CMP6738\/files\/1\/AZUD-Technical_sheet-AZUD_META.pdf","hoja_tecnica_1_nombre":"Ficha t\u00e9cnica AZUD META","descargas_miniatura1":"","hoja_tecnica_2_nombre":"","descargas_miniatura2":"","hoja_tecnica_2_url":"","descargas-tipodedocumento2":"","descargas_tipo_de_documento":"","productos_filtro":"Riego","productos_riego":"Contadores","productos_tipo_de_tuberia":"","productos_autocompensacion":"","productos_ciclo_de_vida_del_cultivo":"","productos_filtracion":"","productos_tecnologia_de_filtracion":"","productos_material":"","_wpml_import_language_code":"","_wpml_import_source_language_code":"","_wpml_import_translation_group":"","orden-producto":"40","visible":[]},"class_list":["post-24599","productos","type-productos","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/productos\/24599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/productos"}],"about":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/types\/productos"}],"version-history":[{"count":0,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/productos\/24599\/revisions"}],"wp:attachment":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=24599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}