{"id":69254,"date":"2026-05-13T18:12:51","date_gmt":"2026-05-13T18:12:51","guid":{"rendered":"https:\/\/azud.com\/passaporte-de-sustentabilidade-azud-sprint\/"},"modified":"2026-07-08T12:39:59","modified_gmt":"2026-07-08T12:39:59","slug":"passaporte-de-sustentabilidade-azud-sprint","status":"publish","type":"page","link":"https:\/\/azud.com\/pt-pt\/passaporte-de-sustentabilidade-azud-sprint\/","title":{"rendered":"Certificado de sustentabilidade AZUD SPRINT"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"69254\" class=\"elementor elementor-69254 elementor-62564\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d91795e e-con-full e-flex e-con e-parent\" data-id=\"d91795e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7b1649 elementor-widget elementor-widget-html\" data-id=\"b7b1649\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\r\n    (function () {\r\n      const root = document.currentScript.closest(\".azud-passport-widget\");\r\n      if (!root) return;\r\n\r\n      const products = {\r\n        \"azud-tub\": {\r\n          name: \"AZUD TUB\",\r\n          heroImage: \"img\/escaparate\/OLANET AZUD TUB.png\",\r\n          materialProduct: \"Polietileno de baja densidad (LDPE-04)\",\r\n          productRecycled: \"0%\",\r\n          materialPackaging:\r\n            \"Polipropileno (PP-05)<br \/>Polietileno de baja densidad (LDPE-04)\",\r\n          packagingRecycled: \"0%\",\r\n          endProductFeatures: [\r\n            \"Dise\u00f1o monomaterial para facilitar el reciclaje.\"\r\n          ],\r\n          endPackagingFeatures: [\r\n            \"Dise\u00f1o con materiales f\u00e1cilmente separables.\",\r\n            \"Embalaje conforme al Reglamento de Envases y Residuos de Envases de la UE.\"\r\n          ],\r\n          recyclableProduct: \"97%\",\r\n          recyclablePackaging: \"70%\",\r\n          noIso9261: true\r\n        },\r\n        \"azud-pc-system\": {\r\n          name: \"AZUD PC SYSTEM\",\r\n          heroImage: \"img\/escaparate\/AZUD PC SYSTEM.png\",\r\n          materialProduct:\r\n            \"Polietileno de alta densidad <br \/>Polietileno de baja densidad (LDPE-04)<br \/>Silicona (LSR)\",\r\n          productRecycled: \"0%\",\r\n          materialPackaging:\r\n            \"Polipropileno (PP-05)<br \/>Polietileno de baja densidad (LDPE-04)\",\r\n          packagingRecycled: \"0%\",\r\n          endProductFeatures: [\r\n            \"Dise\u00f1o optimizado para reciclabilidad t\u00e9cnica.\"\r\n          ],\r\n          endPackagingFeatures: [\r\n            \"Dise\u00f1o con materiales f\u00e1cilmente separables.\",\r\n            \"Embalaje conforme al Reglamento de Envases y Residuos de Envases de la UE.\"\r\n          ],\r\n          recyclableProduct: \"97%\",\r\n          recyclablePackaging: \"70%\",\r\n          noIso9261: true\r\n        }\r\n      };\r\n\r\n      const params = new URLSearchParams(window.location.search);\r\n      const key = params.get(\"product\");\r\n      const product = key ? products[key] : null;\r\n\r\n      if (product) {\r\n        document.title = product.name + \" | Pasaporte de Sostenibilidad\";\r\n\r\n        const h1 = root.querySelector(\".hero-card h1\");\r\n        if (h1) h1.textContent = product.name;\r\n\r\n        const heroImage = root.querySelector(\".hero-card__product\");\r\n        if (heroImage) {\r\n          heroImage.src = product.heroImage;\r\n          heroImage.alt = \"Producto \" + product.name;\r\n        }\r\n\r\n        const materialBlocks = root.querySelectorAll(\".materials-grid .material-block\");\r\n\r\n        if (materialBlocks.length >= 2) {\r\n          const productBlock = materialBlocks[0];\r\n          const packagingBlock = materialBlocks[1];\r\n\r\n          const productStats = productBlock.querySelectorAll(\".stats-list__item dd\");\r\n          if (productStats.length >= 2) {\r\n            productStats[0].innerHTML = product.materialProduct;\r\n            productStats[1].textContent = product.productRecycled;\r\n          }\r\n\r\n          const packagingStats = packagingBlock.querySelectorAll(\".stats-list__item dd\");\r\n          if (packagingStats.length >= 2) {\r\n            packagingStats[0].innerHTML = product.materialPackaging;\r\n            packagingStats[1].textContent = product.packagingRecycled;\r\n          }\r\n\r\n          const productRing = productBlock.querySelector(\".metric-ring\");\r\n          if (productRing) {\r\n            productRing.style.setProperty(\"--progress\", product.productRecycled);\r\n            const value = productRing.querySelector(\".metric-ring__value\");\r\n            if (value) value.textContent = product.productRecycled;\r\n          }\r\n\r\n          const packagingRing = packagingBlock.querySelector(\".metric-ring\");\r\n          if (packagingRing) {\r\n            packagingRing.style.setProperty(\"--progress\", product.packagingRecycled);\r\n            const value = packagingRing.querySelector(\".metric-ring__value\");\r\n            if (value) value.textContent = product.packagingRecycled;\r\n          }\r\n        }\r\n\r\n        const productList = root.querySelector(\".js-end-product-list\");\r\n        if (productList) {\r\n          productList.innerHTML = product.endProductFeatures\r\n            .map((item) => \"<li>\" + item + \"<\/li>\")\r\n            .join(\"\");\r\n        }\r\n\r\n        const packagingList = root.querySelector(\".js-end-packaging-list\");\r\n        if (packagingList) {\r\n          packagingList.innerHTML = product.endPackagingFeatures\r\n            .map((item) => \"<li>\" + item + \"<\/li>\")\r\n            .join(\"\");\r\n        }\r\n\r\n        const recyclableProductRing = root.querySelector(\".js-recyclable-product\");\r\n        if (recyclableProductRing) {\r\n          recyclableProductRing.style.setProperty(\"--progress\", product.recyclableProduct);\r\n          const value = recyclableProductRing.querySelector(\".metric-ring__value\");\r\n          if (value) value.textContent = product.recyclableProduct;\r\n        }\r\n\r\n        const recyclablePackagingRing = root.querySelector(\".js-recyclable-packaging\");\r\n        if (recyclablePackagingRing) {\r\n          recyclablePackagingRing.style.setProperty(\"--progress\", product.recyclablePackaging);\r\n          const value = recyclablePackagingRing.querySelector(\".metric-ring__value\");\r\n          if (value) value.textContent = product.recyclablePackaging;\r\n        }\r\n\r\n        if (product.noIso9261) {\r\n          root\r\n            .querySelectorAll(\".cert-card--iso9261\")\r\n            .forEach((card) => {\r\n              const group = card.closest(\".certification-group\");\r\n              if (group) group.style.display = \"none\";\r\n            });\r\n        }\r\n      }\r\n\r\n      const btn = root.querySelector(\"#print-passport\");\r\n      if (!btn) return;\r\n\r\n      btn.addEventListener(\"click\", () => {\r\n        window.print();\r\n      });\r\n    })();\r\n  <\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aee84ed elementor-widget elementor-widget-html\" data-id=\"aee84ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"azud-passport-widget\">\r\n  <main class=\"passport\">\r\n    <section class=\"hero-card\">\r\n      <div class=\"hero-card__content\">\r\n        <div class=\"hero-card__copy\">\r\n          <p class=\"eyebrow\">Passaporte de Sustentabilidade<\/p>\r\n\r\n          <div class=\"hero-card__title-group\">\r\n            <img decoding=\"async\" class=\"hero-card-img\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/LOGO-AZUD-SPRINT.webp\" alt=\"Log\u00f3tipo da AZUD SPRINT\" \/>\r\n          <\/div>\r\n\r\n          <p class=\"hero-card__description\">\r\n            Ficha digital de sustentabilidade com informa\u00e7\u00f5es sobre materiais, impacto, fim de\r\nvida e certifica\u00e7\u00f5es do produto.\r\n <\/p>\r\n\r\n          <div class=\"hero-card__actions\">\r\n            <a class=\"badge badge--link\" href=\"#formulario-contacto\">\r\n              Solicitar um passaporte com validade prolongada\r\n <\/a>\r\n          <\/div>\r\n        <\/div>\r\n\r\n        <div class=\"hero-card__media\" aria-hidden=\"true\">\r\n          <img decoding=\"async\" class=\"hero-card__product\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/OLANET-AZUD-SPRINT.webp\" alt=\"\" \/>\r\n        <\/div>\r\n      <\/div>\r\n    <\/section>\r\n\r\n    <div class=\"passport-grid\">\r\n      <details class=\"card card--materials card-accordion\" aria-labelledby=\"materials-title\">\r\n        <summary class=\"card-accordion__summary\">\r\n          <div class=\"section-heading\">\r\n            <p class=\"section-heading__eyebrow\">Materiais<\/p>\r\n            <h2 id=\"materials-title\">Materiais do produto e da embalagem<\/h2>\r\n          <\/div>\r\n        <\/summary>\r\n\r\n        <div class=\"card-accordion__content\">\r\n          <section class=\"materials-subsection\" aria-labelledby=\"materials-composition-title\">\r\n            <h3 class=\"materials-subsection__title\" id=\"materials-composition-title\">\r\n              <span class=\"materials-subsection__icon\" aria-hidden=\"true\">\r\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"18\" height=\"18\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\r\n                  <path d=\"M4 6h16\" \/>\r\n                  <path d=\"M4 12h16\" \/>\r\n                  <path d=\"M4 18h16\" \/>\r\n                <\/svg>\r\n              <\/span>\r\n              Composi\u00e7\u00e3o\r\n <\/h3>\r\n\r\n            <div class=\"materials-grid\">\r\n              <article class=\"material-block\">\r\n                <div class=\"material-block__header\">\r\n                  <div>\r\n                    <p class=\"material-block__label\">Produto<\/p>\r\n                  <\/div>\r\n\r\n                  <div class=\"metric-ring\" style=\"--progress: 0%; display: none;\">\r\n                    <span class=\"metric-ring__icon\" aria-hidden=\"true\">&#9851;<\/span>\r\n                    <span class=\"metric-ring__value\">0%<\/span>\r\n                  <\/div>\r\n                <\/div>\r\n\r\n                <div class=\"material-block__body\">\r\n                  <div class=\"material-block__media\">\r\n                    <img decoding=\"async\" class=\"material-block__image\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/OLANET-AZUD-SPRINT.webp\" alt=\"Bobina do produto AZUD SPRINT\" loading=\"lazy\" \/>\r\n                  <\/div>\r\n\r\n                  <dl class=\"stats-list\">\r\n                    <div class=\"stats-list__item\">\r\n                      <dt>Material<\/dt>\r\n                      <dd>Polietileno de alta densidade<\/dd>\r\n                    <\/div>\r\n\r\n                    <div class=\"stats-list__item\">\r\n                      <dt>Material totalmente reciclado<\/dt>\r\n                      <dd>0%<\/dd>\r\n                    <\/div>\r\n                  <\/dl>\r\n                <\/div>\r\n              <\/article>\r\n\r\n              <article class=\"material-block\">\r\n                <div class=\"material-block__header\">\r\n                  <div>\r\n                    <p class=\"material-block__label\">Embalagem<\/p>\r\n                  <\/div>\r\n\r\n                  <div class=\"metric-ring metric-ring--strong\" style=\"--progress: 90%; display: none;\">\r\n                    <span class=\"metric-ring__icon\" aria-hidden=\"true\">&#9851;<\/span>\r\n                    <span class=\"metric-ring__value\">90%<\/span>\r\n                  <\/div>\r\n                <\/div>\r\n\r\n                <div class=\"material-block__body\">\r\n                  <div class=\"material-block__media\">\r\n                    <img decoding=\"async\" class=\"material-block__image material-block__image--packaging\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/palet_bobina-AZUD-SPRINT.webp\" alt=\"Embalagem do produto AZUD SPRINT em palete\" loading=\"lazy\" \/>\r\n                  <\/div>\r\n\r\n                  <dl class=\"stats-list\">\r\n                    <div class=\"stats-list__item\">\r\n                      <dt>Materiais<\/dt>\r\n                      <dd>Cart\u00e3o ondulado (PAP-20)<\/dd>\r\n                      <dd>Cart\u00e3o n\u00e3o ondulado (PAP-21)<\/dd>\r\n                      <dd>Polietileno de baixa densidade (LDPE-04)<\/dd>\r\n                      <dd>Madeira (FOR-50)<\/dd>\r\n                      \r\n                    <\/div>\r\n\r\n                    <div class=\"stats-list__item\">\r\n                      <dt>Material totalmente reciclado<\/dt>\r\n                      <dd>90%<\/dd>\r\n                    <\/div>\r\n                  <\/dl>\r\n                <\/div>\r\n              <\/article>\r\n            <\/div>\r\n          <\/section>\r\n\r\n          <section class=\"materials-subsection\" aria-labelledby=\"materials-end-of-life-title\">\r\n            <h3 class=\"materials-subsection__title\" id=\"materials-end-of-life-title\">\r\n              <span class=\"materials-subsection__icon\" aria-hidden=\"true\">\r\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"18\" height=\"18\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\r\n                  <path d=\"M12 2v4\" \/>\r\n                  <path d=\"M18.36 5.64l-2.83 2.83\" \/>\r\n                  <path d=\"M22 12h-4\" \/>\r\n                  <path d=\"M18.36 18.36l-2.83 -2.83\" \/>\r\n                  <path d=\"M12 22v-4\" \/>\r\n                  <path d=\"M5.64 18.36l2.83 -2.83\" \/>\r\n                  <path d=\"M2 12h4\" \/>\r\n                  <path d=\"M5.64 5.64l2.83 2.83\" \/>\r\n                  <circle cx=\"12\" cy=\"12\" r=\"3\" \/>\r\n                <\/svg>\r\n              <\/span>\r\n              Fim da vida\r\n <\/h3>\r\n\r\n            <div class=\"end-of-life-grid\">\r\n              <article class=\"end-of-life-block\">\r\n                <p class=\"material-block__label\">Produto<\/p>\r\n\r\n                <div class=\"end-of-life-section\">\r\n                  <p class=\"end-of-life-section__label\">Fim do ciclo de vida do produto<\/p>\r\n                  <ul class=\"feature-list feature-list--compact js-end-product-list\">\r\n                    <li>Design monomaterial para facilitar a reciclagem.<\/li>\r\n                  <\/ul>\r\n                <\/div>\r\n\r\n                <div class=\"end-of-life-section\">\r\n                  <div class=\"end-of-life-label-with-tooltip\">\r\n                    <p class=\"end-of-life-section__label\">Tecnicamente recicl\u00e1vel<\/p>\r\n\r\n                    <button class=\"info-tooltip-trigger\" type=\"button\" aria-label=\"M\u00e1s informaci\u00f3n sobre reciclable t\u00e9cnicamente\" aria-describedby=\"tooltip-recyclable-tech-product\">\r\n                      i\r\n <\/button>\r\n\r\n                    <span class=\"info-tooltip-box\" id=\"tooltip-recyclable-tech-product\" role=\"tooltip\">\r\n                      Condi\u00e7\u00f5es t\u00e9cnicas para a sua separa\u00e7\u00e3o, tratamento e valoriza\u00e7\u00e3o dos materiais no final da sua vida \u00fatil.\r\n <\/span>\r\n                  <\/div>\r\n\r\n                  <div class=\"end-of-life-metric\">\r\n                    <div class=\"metric-ring metric-ring--end-of-life js-recyclable-product\" style=\"--progress: 97%\">\r\n                      <span class=\"metric-ring__icon\" aria-hidden=\"true\">&#9851;<\/span>\r\n                      <span class=\"metric-ring__value\">97%<\/span>\r\n                    <\/div>\r\n                  <\/div>\r\n                <\/div>\r\n\r\n                <div class=\"end-of-life-section end-of-life-section--logos\">\r\n                  <p class=\"end-of-life-section__label\">Sistema de gest\u00e3o do fim de vida \u00fatil<\/p>\r\n\r\n                  <div class=\"recyclable-logos\">\r\n                    <img decoding=\"async\" class=\"recyclable-logos__item recyclable-logos__item--erde\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/erde_germany.webp\" alt=\"Log\u00f3tipo da ERDE Germany\" loading=\"lazy\" \/>\r\n\r\n                    <img decoding=\"async\" class=\"recyclable-logos__item recyclable-logos__item--cpa\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/cpa-logo.svg\" alt=\"Log\u00f3tipo da CPA\" loading=\"lazy\" \/>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/article>\r\n\r\n              <article class=\"end-of-life-block\">\r\n                <p class=\"material-block__label\">Embalagem<\/p>\r\n\r\n                <div class=\"end-of-life-section\">\r\n                  <p class=\"end-of-life-section__label\">Fim da vida \u00fatil da embalagem<\/p>\r\n\r\n                  <ul class=\"feature-list feature-list--compact js-end-packaging-list\">\r\n                    <li>Design com materiais facilmente separ\u00e1veis.<\/li>\r\n                    <li>\r\n                      Embalagem em conformidade com o Regulamento da UE relativo \u00e0s Embalagens e aos Res\u00edduos de\r\n Embalagens.\r\n <\/li>\r\n                  <\/ul>\r\n                <\/div>\r\n\r\n                <div class=\"end-of-life-section\">\r\n                  <div class=\"end-of-life-label-with-tooltip\">\r\n                    <p class=\"end-of-life-section__label\">Tecnicamente recicl\u00e1vel<\/p>\r\n\r\n                    <button class=\"info-tooltip-trigger\" type=\"button\" aria-label=\"M\u00e1s informaci\u00f3n sobre reciclable t\u00e9cnicamente\" aria-describedby=\"tooltip-recyclable-tech-packaging\">\r\n                      i\r\n <\/button>\r\n\r\n                    <span class=\"info-tooltip-box\" id=\"tooltip-recyclable-tech-packaging\" role=\"tooltip\">\r\n                      Condi\u00e7\u00f5es t\u00e9cnicas para a sua separa\u00e7\u00e3o, tratamento e valoriza\u00e7\u00e3o dos materiais no final da sua vida \u00fatil.\r\n <\/span>\r\n                  <\/div>\r\n\r\n                  <div class=\"end-of-life-metric\">\r\n                    <div class=\"metric-ring metric-ring--end-of-life js-recyclable-packaging\" style=\"--progress: 70%\">\r\n                      <span class=\"metric-ring__icon\" aria-hidden=\"true\">&#9851;<\/span>\r\n                      <span class=\"metric-ring__value\">70%<\/span>\r\n                    <\/div>\r\n                  <\/div>\r\n                <\/div>\r\n              <\/article>\r\n            <\/div>\r\n          <\/section>\r\n        <\/div>\r\n      <\/details>\r\n\r\n      <details class=\"card card--impact card-accordion\" aria-labelledby=\"impact-title\">\r\n        <summary class=\"card-accordion__summary\">\r\n          <div class=\"section-heading\">\r\n            <p class=\"section-heading__eyebrow\">Impacto<\/p>\r\n            <h2 id=\"impact-title\">Indicadores de sustentabilidade e impacto<\/h2>\r\n          <\/div>\r\n        <\/summary>\r\n\r\n        <div class=\"card-accordion__content\">\r\n          <div class=\"impact-grid\">\r\n            <article class=\"impact-item\">\r\n              <span class=\"impact-item__icon\" aria-hidden=\"true\">\r\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"#91e0d2\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\r\n                  <path stroke=\"none\" d=\"M0 0h24v24H0z\" fill=\"none\" \/>\r\n                  <path d=\"M13 3l0 7l6 0l-8 11l0 -7l-6 0l8 -11\" \/>\r\n                <\/svg>\r\n              <\/span>\r\n\r\n              <h3>Energia sustent\u00e1vel<\/h3>\r\n              <p>Indicadores de efici\u00eancia energ\u00e9tica avaliados internamente.<\/p>\r\n            <\/article>\r\n\r\n            <article class=\"impact-item\">\r\n              <span class=\"impact-item__icon\" aria-hidden=\"true\">\r\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"#91e0d2\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\r\n                  <path stroke=\"none\" d=\"M0 0h24v24H0z\" fill=\"none\" \/>\r\n                  <path d=\"M7.502 19.423c2.602 2.105 6.395 2.105 8.996 0c2.602 -2.105 3.262 -5.708 1.566 -8.546l-4.89 -7.26c-.42 -.625 -1.287 -.803 -1.936 -.397a1.376 1.376 0 0 0 -.41 .397l-4.893 7.26c-1.695 2.838 -1.035 6.441 1.567 8.546\" \/>\r\n                <\/svg>\r\n              <\/span>\r\n\r\n              <h3>Pegada h\u00eddrica<\/h3>\r\n              <p>Calculada para o processo interno de produ\u00e7\u00e3o da AZUD.<\/p>\r\n            <\/article>\r\n\r\n            <article class=\"impact-item\">\r\n              <span class=\"impact-item__icon\" aria-hidden=\"true\">\r\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"#91e0d2\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\r\n                  <path stroke=\"none\" d=\"M0 0h24v24H0z\" fill=\"none\" \/>\r\n                  <path d=\"M12 10a6 6 0 0 0 -6 -6h-3v2a6 6 0 0 0 6 6h3\" \/>\r\n                  <path d=\"M12 14a6 6 0 0 1 6 -6h3v1a6 6 0 0 1 -6 6h-3\" \/>\r\n                  <path d=\"M12 20l0 -10\" \/>\r\n                <\/svg>\r\n              <\/span>\r\n\r\n              <h3>Pegada de carbono<\/h3>\r\n              <p>Emiss\u00f5es diretas e indiretas medidas para o produto.<\/p>\r\n            <\/article>\r\n\r\n            <article class=\"impact-item\">\r\n              <span class=\"impact-item__icon\" aria-hidden=\"true\">\r\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"#91e0d2\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\r\n                  <path stroke=\"none\" d=\"M0 0h24v24H0z\" fill=\"none\" \/>\r\n                  <path d=\"M7 16.5l-5 -3l5 -3l5 3v5.5l-5 3l0 -5.5\" \/>\r\n                  <path d=\"M2 13.5v5.5l5 3\" \/>\r\n                  <path d=\"M7 16.545l5 -3.03\" \/>\r\n                  <path d=\"M17 16.5l-5 -3l5 -3l5 3v5.5l-5 3l0 -5.5\" \/>\r\n                  <path d=\"M12 19l5 3\" \/>\r\n                  <path d=\"M17 16.5l5 -3\" \/>\r\n                  <path d=\"M12 13.5v-5.5l-5 -3l5 -3l5 3v5.5\" \/>\r\n                  <path d=\"M7 5.03v5.455\" \/>\r\n                  <path d=\"M12 8l5 -3\" \/>\r\n                <\/svg>\r\n              <\/span>\r\n\r\n              <h3>Taxa de embalagem<\/h3>\r\n              <p>Lista de embalagens calculada e dispon\u00edvel mediante pedido.<\/p>\r\n            <\/article>\r\n          <\/div>\r\n\r\n          <a class=\"badge badge--link impact-cta\" style=\"display: none;\" href=\"#formulario-contacto\">\r\n            Saiba mais sobre os indicadores de sustentabilidade deste produto\r\n <\/a>\r\n        <\/div>\r\n      <\/details>\r\n\r\n      <details class=\"card certification-proposal card-accordion\" aria-labelledby=\"certs-proposal-title\">\r\n        <summary class=\"card-accordion__summary\">\r\n          <div class=\"section-heading\">\r\n            <p class=\"section-heading__eyebrow\">Garantia e transpar\u00eancia<\/p>\r\n            <h2 id=\"certs-proposal-title\">Certifica\u00e7\u00f5es e compromissos<\/h2>\r\n          <\/div>\r\n        <\/summary>\r\n\r\n        <div class=\"card-accordion__content\">\r\n          <div class=\"certification-proposal__layout\">\r\n            <div class=\"certification-proposal__top\">\r\n              <article class=\"certification-proposal__featured\">\r\n                <h3>Certifica\u00e7\u00e3o do produto<\/h3>\r\n\r\n                <img decoding=\"async\" style=\"width: 250px;\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/AENOR_equiposderiego-OFICIALES-con-ISO-9261_HOZ_POS-1.webp\" alt=\"Certifica\u00e7\u00e3o AENOR \u2013 produto certificado segundo a norma ISO 9261\" loading=\"lazy\" \/>\r\n              <\/article>\r\n\r\n              <section class=\"certification-proposal__panel\" aria-labelledby=\"certs-voluntary-proposal-title\">\r\n                <h3 id=\"certs-voluntary-proposal-title\">Participa\u00e7\u00e3o em iniciativas<\/h3>\r\n\r\n                <div class=\"certification-proposal__initiatives\">\r\n                  <article>\r\n                    <img decoding=\"async\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/UNGC-ENDORSER-ES-Mundial-RGB-1.webp\" alt=\"Pacto Mundial das Na\u00e7\u00f5es Unidas\" loading=\"lazy\" \/>\r\n                  <\/article>\r\n\r\n                  <article>\r\n                    <img decoding=\"async\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/operation-clean-sweep-logo.avif\" alt=\"Opera\u00e7\u00e3o Clean Sweep\" loading=\"lazy\" \/>\r\n                  <\/article>\r\n                <\/div>\r\n              <\/section>\r\n            <\/div>\r\n\r\n<section class=\"certification-proposal__panel certification-proposal__panel--management\" aria-labelledby=\"certs-management-proposal-title\">\r\n  <h3 id=\"certs-management-proposal-title\">Certifica\u00e7\u00f5es de sistemas de gest\u00e3o<\/h3>\r\n\r\n  <div class=\"certification-proposal__carousel\" aria-label=\"Carrusel de certificaciones de sistemas de gesti\u00f3n\">\r\n    <button type=\"button\" class=\"certification-proposal__carousel-arrow certification-proposal__carousel-arrow--prev\" aria-label=\"Retroceder\">\r\n      <svg viewBox=\"0 0 24 24\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M15 5l-7 7 7 7\" \/><\/svg>\r\n    <\/button>\r\n\r\n    <div class=\"certification-proposal__carousel-viewport\">\r\n      <div class=\"certification-proposal__carousel-track\">\r\n        <article class=\"certification-proposal__carousel-slide\">\r\n          <img decoding=\"async\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/AENOR_gestion_calidad.webp\" alt=\"ISO 9001 AENOR\" loading=\"lazy\" \/>\r\n        <\/article>\r\n        <article class=\"certification-proposal__carousel-slide\">\r\n          <img decoding=\"async\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/AENOR_gestion_ambiental.webp\" alt=\"ISO 14001 AENOR\" loading=\"lazy\" \/>\r\n        <\/article>\r\n        <article class=\"certification-proposal__carousel-slide\">\r\n          <img decoding=\"async\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/AENOR_seguridad_salud.webp\" alt=\"ISO 45001 AENOR\" loading=\"lazy\" \/>\r\n        <\/article>\r\n        <article class=\"certification-proposal__carousel-slide\">\r\n          <img decoding=\"async\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/06\/RESIDUO-CERO.webp\" alt=\"Zero Res\u00edduos\" loading=\"lazy\" \/>\r\n        <\/article>\r\n        <article class=\"certification-proposal__carousel-slide\">\r\n          <img decoding=\"async\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/Sello-Huella-de-Carbono-2024.webp\" alt=\"Pegada de carbono\" loading=\"lazy\" \/>\r\n        <\/article>\r\n        <article class=\"certification-proposal__carousel-slide\">\r\n          <img decoding=\"async\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/2025-02-Insignia-Committed-CSR.webp\" alt=\"EcoVadis\" loading=\"lazy\" \/>\r\n        <\/article>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <button type=\"button\" class=\"certification-proposal__carousel-arrow certification-proposal__carousel-arrow--next\" aria-label=\"Avanzar\">\r\n      <svg viewBox=\"0 0 24 24\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M9 5l7 7-7 7\" \/><\/svg>\r\n    <\/button>\r\n  <\/div>\r\n<\/section>\r\n\r\n\r\n          <\/div>\r\n        <\/div>\r\n      <\/details>\r\n    <\/div>\r\n\r\n <section class=\"contact-band\" id=\"formulario-contacto\" aria-labelledby=\"contact-title\">\r\n      <div class=\"contact-band__card\">\r\n        <div class=\"contact-band__layout\">\r\n          <aside class=\"contact-band__info-column\" aria-label=\"Beneficios del pasaporte ampliado\">\r\n            <h2 id=\"contact-title\">Solicite o seu passaporte com validade prolongada<\/h2>\r\n\r\n            <p class=\"contact-band__text\">\r\n              Deixe-nos os seus dados e entraremos em contacto consigo para lhe fornecer mais informa\u00e7\u00f5es sobre o produto e o seu passaporte digital. Receber\u00e1:\r\n <\/p>\r\n\r\n            <ul class=\"contact-band__benefits\">\r\n              <li>Informa\u00e7\u00f5es sobre os materiais, a sua composi\u00e7\u00e3o e o seu potencial de reciclagem.<\/li>\r\n              <li>Aceda a indicadores-chave de impacto, tais como a pegada de carbono, o consumo de \u00e1gua e a efici\u00eancia energ\u00e9tica.<\/li>\r\n              <li>Detalhes sobre a gest\u00e3o do fim de vida do produto e a sua integra\u00e7\u00e3o em modelos de economia circular.<\/li>\r\n              <li>Informa\u00e7\u00f5es sobre o enquadramento normativo, as certifica\u00e7\u00f5es e os sistemas de gest\u00e3o que garantem a qualidade de cada gama.<\/li>\r\n            <\/ul>\r\n          <\/aside>\r\n\r\n       <div class=\"formulario-pasaporte-sostenibilidad\"> \r\n    \t\t<div data-elementor-type=\"container\" data-elementor-id=\"65556\" class=\"elementor elementor-65556 elementor-65317 elementor-65317\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b03cf0 e-flex e-con-boxed e-con e-parent\" data-id=\"5b03cf0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17030c6 elementor-widget elementor-widget-html\" data-id=\"17030c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe \r\n  name=\"pagina_puente_iframe\" \r\n  id=\"pagina_puente_iframe\" \r\n  class=\"iframe-responsive-crm F2\"\r\n  scrolling=\"yes\"\r\n><\/iframe>\r\n\r\n<form id=\"form_hacia_puente\" action=\"https:\/\/awgapi.azud.com\/api_form_CRM\/iframe_formCD.php\" method=\"POST\" target=\"pagina_puente_iframe\" style=\"display:none;\">\r\n  <input type=\"hidden\" name=\"dato_session\" id=\"input_session\" value=\"\">\r\n  \r\n  <input type=\"hidden\" name=\"tipo_form\" value=\"F2\">\r\n  \r\n<input type=\"hidden\" name=\"lang\" id=\"input_lang\" value=\"es\">\r\n\r\n <input type=\"hidden\" name=\"url_name\" id=\"input_url_name\" value=\"\">\r\n\r\n<\/form>\r\n\r\n<script>\r\n  (function() {\r\n    function detectarIdioma() {\r\n      const path = window.location.pathname.toLowerCase();\r\n\r\n      if (path.startsWith('\/en\/')) return 'en';\r\n      if (path.startsWith('\/fr\/')) return 'fr';\r\n      if (path.startsWith('\/pt-pt\/')) return 'pt';\r\n      if (path.startsWith('\/it\/')) return 'it';\r\n      if (path.startsWith('\/de\/')) return 'de';\r\n\r\n      return 'es';\r\n    }\r\n\r\n    function enviarFormularioPuente() {\r\n      const valorSession = sessionStorage.getItem('azud_tracking_menu'); \r\n      const input = document.getElementById('input_session');\r\n      const inputLang = document.getElementById('input_lang');\r\n\t  const inputUrlName = document.getElementById('input_url_name');\r\n      const form = document.getElementById('form_hacia_puente');\r\n\r\n const hasConsent = typeof cmplz_has_consent === 'function' ? cmplz_has_consent('marketing') : false;\r\n      \r\n        \r\n      if (inputLang) {\r\n        inputLang.value = detectarIdioma();\r\n      }\r\n\r\n      if (input && form) {\r\n\t  \r\n\t\tif (hasConsent){\r\n\t\t\tif (valorSession) {\r\n\t\t\t\tinput.value = valorSession;\r\n\t\t\t}\r\n\t\t\t\r\n\t\t\tif (inputUrlName) {\r\n\t\t\t\tinputUrlName.value = window.location.href;\r\n\t\t\t}\r\n\t\t\t\t\r\n\t\t}\r\n\t\tform.action = \"https:\/\/awgapi.azud.com\/api_form_CRM\/iframe_formCD.php?v=\" + new Date().getTime() + \"&consent=\" + hasConsent;\r\n\t\tform.submit();\r\n      }\r\n    }\r\n\r\n    if (document.readyState === \"loading\") {\r\n        \r\n      document.addEventListener(\"DOMContentLoaded\", function() {\r\n        setTimeout(enviarFormularioPuente, 100);\r\n      });\r\n    } else {\r\n      setTimeout(enviarFormularioPuente, 100);\r\n      \r\n    }\r\n  })();\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n<\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/section>\r\n\r\n  <\/main>\r\n\r\n  \r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Passaporte de Sustentabilidade Ficha digital de sustentabilidade com informa\u00e7\u00f5es sobre materiais, impacto, fim de vida e certifica\u00e7\u00f5es do produto. Solicitar um passaporte com validade prolongada Materiais Materiais do produto e da embalagem Composi\u00e7\u00e3o Produto &#9851; 0% Material Polietileno de alta densidade Material totalmente reciclado 0% Embalagem &#9851; 90% Materiais Cart\u00e3o ondulado (PAP-20) Cart\u00e3o n\u00e3o ondulado [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-69254","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/pages\/69254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=69254"}],"version-history":[{"count":2,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/pages\/69254\/revisions"}],"predecessor-version":[{"id":77644,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/pages\/69254\/revisions\/77644"}],"wp:attachment":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=69254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}