{"id":74754,"date":"2026-05-14T11:06:03","date_gmt":"2026-05-14T11:06:03","guid":{"rendered":"https:\/\/azud.com\/casos-de-exito\/aproveitamento-da-agua-de-drenagem-no-cultivo-hidroponico-de-morangos-para-melhorar-a-rentabilidade\/"},"modified":"2026-07-07T10:50:11","modified_gmt":"2026-07-07T10:50:11","slug":"aproveitamento-da-agua-de-drenagem-no-cultivo-hidroponico-de-morangos-para-melhorar-a-rentabilidade","status":"publish","type":"caso-de-exito","link":"https:\/\/azud.com\/pt-pt\/casos-de-sucesso\/aproveitamento-da-agua-de-drenagem-no-cultivo-hidroponico-de-morangos-para-melhorar-a-rentabilidade\/","title":{"rendered":"Aproveitamento da \u00e1gua de drenagem no cultivo hidrop\u00f3nico de morangos para melhorar a rentabilidade"},"featured_media":74807,"menu_order":0,"template":"","meta":{"compania_titulo_":"Quinta de morangos","compania_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/28.webp","compania_texto":"<p>\u00a0<\/p>\n<p>Produtor de morangos em cultivo hidrop\u00f3nico, com uma explora\u00e7\u00e3o de grande escala (40 ha), situada numa regi\u00e3o com forte stress h\u00eddrico, na Baixa Calif\u00f3rnia (M\u00e9xico).<\/p>\n<p>O seu modelo produtivo \u00e9 fortemente condicionado pela disponibilidade e pelo custo da \u00e1gua, o que torna imprescind\u00edvel a implementa\u00e7\u00e3o de solu\u00e7\u00f5es que otimizem a sua utiliza\u00e7\u00e3o e garantam a rentabilidade.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","el_reto_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/Casos-de-exito-2-1.webp","compania_texto_copy":"<p>\u00a0<\/p>\n<p>A explora\u00e7\u00e3o enfrentava uma situa\u00e7\u00e3o cr\u00edtica no que diz respeito aos recursos h\u00eddricos:<\/p>\n<ul>\n<li><strong>\u00danica fonte de \u00e1gua<\/strong>: um po\u00e7o com \u00e1gua de elevada condutividade.<\/li>\n<li>Necessidade de <strong>dessaliniza\u00e7\u00e3o pr\u00e9via<\/strong> para poder utilizar a \u00e1gua na rega.<\/li>\n<li><strong>Custos elevados de energia<\/strong>, tanto no que diz respeito ao bombeamento da \u00e1gua como ao processo de tratamento.<\/li>\n<\/ul>\n<p>Neste contexto, o custo da \u00e1gua representava um fator limitante para a rentabilidade do cultivo.<\/p>\n<p>O desafio era claro: reduzir o custo de obten\u00e7\u00e3o da \u00e1gua sem comprometer a qualidade nem a produ\u00e7\u00e3o, recorrendo a fontes alternativas mais eficientes.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","la_solucion_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/Recypack-3.webp","la_solucion_texto":"<p>\u00a0<\/p>\n<p>O produtor apostou na instala\u00e7\u00e3o da unidade de reutiliza\u00e7\u00e3o <strong>AZUD WATERTECH Recypack<\/strong>, destinada \u00e0 recupera\u00e7\u00e3o e tratamento das \u00e1guas de drenagem da cultura hidrop\u00f3nica.<\/p>\n<p>Esta solu\u00e7\u00e3o permitiu transformar o escoamento numa nova fonte de \u00e1gua pot\u00e1vel, gra\u00e7as a:<\/p>\n<ul>\n<li>Pr\u00e9-filtragem com tecnologia de discos.<\/li>\n<li>Microfiltra\u00e7\u00e3o para remo\u00e7\u00e3o de s\u00f3lidos finos.<\/li>\n<li>Desinfe\u00e7\u00e3o avan\u00e7ada, garantindo a seguran\u00e7a fitossanit\u00e1ria.<\/li>\n<\/ul>\n<p>A unidade, totalmente automatizada e do tipo \u00abplug & play\u00bb, integrou-se facilmente nas instala\u00e7\u00f5es existentes, sem aumentar a complexidade operacional.<\/p>\n<p>\u00a0<\/p>\n","beneficios_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2026\/05\/Casos-de-exito-3.webp","beneficios_texto":"<p>\u00a0<\/p>\n<p>A implementa\u00e7\u00e3o do AZUD WATERTECH Recypack teve um impacto direto na efici\u00eancia e na rentabilidade da explora\u00e7\u00e3o:<\/p>\n<ul>\n<li><strong>Reutiliza\u00e7\u00e3o de 40% da \u00e1gua de rega<\/strong>, proveniente dos sistemas de drenagem.<\/li>\n<li>Redu\u00e7\u00e3o significativa da depend\u00eancia da \u00e1gua dessalinizada.<\/li>\n<li><strong>Redu\u00e7\u00e3o dos custos de abastecimento de \u00e1gua<\/strong>, tanto no que diz respeito \u00e0 energia como ao tratamento.<\/li>\n<li>Maior efici\u00eancia na utiliza\u00e7\u00e3o dos recursos h\u00eddricos dispon\u00edveis.<\/li>\n<li>Melhoria da sustentabilidade do sistema produtivo.<\/li>\n<\/ul>\n<p>Gra\u00e7as \u00e0 incorpora\u00e7\u00e3o desta fonte alternativa de \u00e1gua, o produtor conseguiu otimizar os seus custos operacionais e refor\u00e7ar a viabilidade econ\u00f3mica da cultura.<\/p>\n"},"tipo-de-industriacultivos":[888],"subsector-casos-de-exito":[1173,955],"lineas-de-actividad-casos":[960],"soluciones-casos-de-exito":[1172,1171],"sector-casos-de-exito":[1091],"class_list":["post-74754","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","tipo-de-industriacultivos-framboesa","subsector-casos-de-exito-berr","subsector-casos-de-exito-frutos_silvestres","lineas-de-actividad-casos-tratamento_da_agua","soluciones-casos-de-exito-reutilizacao","soluciones-casos-de-exito-reutilizacao-das-aguas-de-drenagem-em-culturas-hidroponicas","sector-casos-de-exito-agricultura-pt"],"_links":{"self":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/74754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"version-history":[{"count":1,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/74754\/revisions"}],"predecessor-version":[{"id":74784,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/74754\/revisions\/74784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media\/74807"}],"wp:attachment":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=74754"}],"wp:term":[{"taxonomy":"tipo-de-industriacultivos","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/tipo-de-industriacultivos?post=74754"},{"taxonomy":"subsector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/subsector-casos-de-exito?post=74754"},{"taxonomy":"lineas-de-actividad-casos","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/lineas-de-actividad-casos?post=74754"},{"taxonomy":"soluciones-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/soluciones-casos-de-exito?post=74754"},{"taxonomy":"sector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/sector-casos-de-exito?post=74754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}