{"id":55825,"date":"2023-04-21T10:49:12","date_gmt":"2023-04-21T10:49:12","guid":{"rendered":"https:\/\/azud.com\/casos-de-exito\/a-volkswagen-reduz-o-tempo-de-paragem-da-producao-protegendo-as-membranas-uf\/"},"modified":"2026-07-07T06:23:01","modified_gmt":"2026-07-07T06:23:01","slug":"a-volkswagen-reduz-o-tempo-de-paragem-da-producao-protegendo-as-membranas-uf","status":"publish","type":"caso-de-exito","link":"https:\/\/azud.com\/pt-pt\/casos-de-sucesso\/a-volkswagen-reduz-o-tempo-de-paragem-da-producao-protegendo-as-membranas-uf\/","title":{"rendered":"A Volkswagen reduz as paragens de produ\u00e7\u00e3o, protegendo as Membranas UF."},"featured_media":32238,"menu_order":0,"template":"","meta":{"compania_titulo_":"Volkswagen","compania_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/10\/Referencias-Volkswagen-1.webp","compania_texto":"<ul>\n<li><strong>Pa\u00eds<\/strong>: M\u00e9xico<\/li>\n<li><strong>Setor de atividade<\/strong>: Ind\u00fastria Autom\u00f3vel<\/li>\n<li><strong>Utilizador final<\/strong>: Volkswagen<\/li>\n<li><strong>Aplica\u00e7\u00e3o<\/strong>: Prote\u00e7\u00e3o das membranas UF<\/li>\n<li><strong>Produto<\/strong>: AZUD HELIX AUTOMATIC FT200 AA DLP INDUSTRIAL<\/li>\n<li><strong>Caudal (m<sup>3<\/sup>\/h)<\/strong>: 120<\/li>\n<\/ul>\n","el_reto_imagen":"","compania_texto_copy":"","la_solucion_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/10\/Referencias-Volkswagen-1.webp","la_solucion_texto":"<p>A prote\u00e7\u00e3o das membranas UF atrav\u00e9s de uma filtra\u00e7\u00e3o pr\u00e9via de 100 micr\u00f3metros permitiu \u00e0 Volkswagen eliminar o risco de obstru\u00e7\u00e3o das fibras da membrana.<\/p>\n","beneficios_imagen":"","beneficios_texto":""},"tipo-de-industriacultivos":[797],"subsector-casos-de-exito":[915],"lineas-de-actividad-casos":[965],"soluciones-casos-de-exito":[990],"sector-casos-de-exito":[1071],"class_list":["post-55825","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","tipo-de-industriacultivos-metalmecanica","subsector-casos-de-exito-industria-metalomecanica","lineas-de-actividad-casos-filtracao","soluciones-casos-de-exito-proteccion-de-membranas-de-ultrafiltracion","sector-casos-de-exito-industrial-pt"],"_links":{"self":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"version-history":[{"count":1,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55825\/revisions"}],"predecessor-version":[{"id":74663,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55825\/revisions\/74663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media\/32238"}],"wp:attachment":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=55825"}],"wp:term":[{"taxonomy":"tipo-de-industriacultivos","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/tipo-de-industriacultivos?post=55825"},{"taxonomy":"subsector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/subsector-casos-de-exito?post=55825"},{"taxonomy":"lineas-de-actividad-casos","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/lineas-de-actividad-casos?post=55825"},{"taxonomy":"soluciones-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/soluciones-casos-de-exito?post=55825"},{"taxonomy":"sector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/sector-casos-de-exito?post=55825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}