{"id":55822,"date":"2023-04-21T11:20:25","date_gmt":"2023-04-21T11:20:25","guid":{"rendered":"https:\/\/azud.com\/casos-de-exito\/a-pedreira-reduz-as-paragens-de-producao-protegendo-as-maquinas-de-lavar\/"},"modified":"2026-07-07T06:23:00","modified_gmt":"2026-07-07T06:23:00","slug":"a-pedreira-reduz-as-paragens-de-producao-protegendo-as-maquinas-de-lavar","status":"publish","type":"caso-de-exito","link":"https:\/\/azud.com\/pt-pt\/casos-de-sucesso\/a-pedreira-reduz-as-paragens-de-producao-protegendo-as-maquinas-de-lavar\/","title":{"rendered":"A Cantera reduz as paragens de produ\u00e7\u00e3o, protegendo as m\u00e1quinas de lavar"},"featured_media":32282,"menu_order":0,"template":"","meta":{"compania_titulo_":"Cantera","compania_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/10\/Referencias-Cantera-minera-1.webp","compania_texto":"<ul>\n<li><strong>Pa\u00eds<\/strong>: Alemanha<\/li>\n<li><strong>Setor de atividade<\/strong>: Ind\u00fastria Mineira<\/li>\n<li><strong>Utilizador final<\/strong>: Ind\u00fastria Mineira<\/li>\n<li><strong>Aplica\u00e7\u00e3o<\/strong>: Filtragem de \u00c1guas de Capta\u00e7\u00e3o<\/li>\n<li><strong>Produto<\/strong>: AZUD HELIX AUTOMATIC FT4DCL DLP INDUSTRIAL<\/li>\n<li><strong>Caudal (m<sup>3<\/sup>\/h)<\/strong>: 270<\/li>\n<\/ul>\n","el_reto_imagen":"","compania_texto_copy":"","la_solucion_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/10\/Referencias-Cantera-minera-1.webp","la_solucion_texto":"<p>A Cantera reduz as paragens para manuten\u00e7\u00e3o, evitando, atrav\u00e9s de filtragem, o entupimento dos bocais durante a lavagem das escavadoras<\/p>\n","beneficios_imagen":"","beneficios_texto":""},"tipo-de-industriacultivos":[],"subsector-casos-de-exito":[],"lineas-de-actividad-casos":[965],"soluciones-casos-de-exito":[1000],"sector-casos-de-exito":[1076],"class_list":["post-55822","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","lineas-de-actividad-casos-filtracao","soluciones-casos-de-exito-filtracion-de-aguas-de-captacion","sector-casos-de-exito-mineracao"],"_links":{"self":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"version-history":[{"count":1,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55822\/revisions"}],"predecessor-version":[{"id":74661,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55822\/revisions\/74661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media\/32282"}],"wp:attachment":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=55822"}],"wp:term":[{"taxonomy":"tipo-de-industriacultivos","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/tipo-de-industriacultivos?post=55822"},{"taxonomy":"subsector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/subsector-casos-de-exito?post=55822"},{"taxonomy":"lineas-de-actividad-casos","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/lineas-de-actividad-casos?post=55822"},{"taxonomy":"soluciones-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/soluciones-casos-de-exito?post=55822"},{"taxonomy":"sector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/sector-casos-de-exito?post=55822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}