{"id":55718,"date":"2025-05-21T10:02:17","date_gmt":"2025-05-21T10:02:17","guid":{"rendered":"https:\/\/azud.com\/casos-de-exito\/rega-no-jardim-vertical-caixaforum-em-madrid\/"},"modified":"2026-07-07T06:23:46","modified_gmt":"2026-07-07T06:23:46","slug":"rega-no-jardim-vertical-caixaforum-em-madrid","status":"publish","type":"caso-de-exito","link":"https:\/\/azud.com\/pt-pt\/casos-de-sucesso\/rega-no-jardim-vertical-caixaforum-em-madrid\/","title":{"rendered":"Irriga\u00e7\u00e3o no Jardim Vertical do CaixaForum, em Madrid"},"featured_media":6699,"menu_order":0,"template":"","meta":{"compania_titulo_":"Funda\u00e7\u00e3o \u00abla caixa\u00bb","compania_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/Foto-2-2-1.webp","compania_texto":"<p>O Jardim Vertical do CaixaForum, em Espanha \u2014 o primeiro e com a maior superf\u00edcie cont\u00ednua do pa\u00eds \u2014, representa uma inova\u00e7\u00e3o significativa na jardinagem urbana. Este jardim tornou-se um \u00edcone de Madrid, albergando 15 000 plantas nos seus 460 m\u00b2 sem necessidade de terra.<\/p>\n<hr \/>\n<p><strong>Localiza\u00e7\u00e3o<\/strong>: Madrid, Espanha<br \/>\n<strong>Ano<\/strong>: 2007<\/p>\n","el_reto_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/Foto-1-6.webp","compania_texto_copy":"<p>Criar um sistema de rega eficiente para um jardim vertical que exija uma distribui\u00e7\u00e3o precisa de \u00e1gua e nutrientes a cada planta. Al\u00e9m disso, pretendia-se que o jardim funcionasse como isolante t\u00e9rmico e sistema de refrigera\u00e7\u00e3o, reduzindo o consumo de energia.<\/p>\n","la_solucion_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/Foto-4-4-1.webp","la_solucion_texto":"<p>A AZUD implementou o seu sistema de <strong>irriga\u00e7\u00e3o por gotejamento anti-drenagem com a tecnologia <a href=\"https:\/\/azud.com\/producto\/navia\/\" target=\"_blank\" rel=\"noopener\">AZUD NAVIA ND<\/a><\/strong>, concebido para se adaptar a instala\u00e7\u00f5es com diferen\u00e7as de n\u00edvel significativas e culturas de alto rendimento.<\/p>\n<p>NAVIA \u00e9 a gama de <strong>gotejadores perfurados, autocompensadores e anti-drenagem<\/strong> que se adapta tanto \u00e0 irriga\u00e7\u00e3o de instala\u00e7\u00f5es com grandes diferen\u00e7as de n\u00edvel como a culturas de alto rendimento em estufas.<\/p>\n<p>Esta tecnologia de ponta combina uma ampla gama de autocompensa\u00e7\u00e3o com uma excelente uniformidade na aplica\u00e7\u00e3o de \u00e1gua e fertilizantes.<\/p>\n","beneficios_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/Foto-3-3-1.webp","beneficios_texto":"<p>O sistema de irriga\u00e7\u00e3o por pulso da AZUD transformou o Jardim Vertical do CaixaForum num exemplo not\u00e1vel de como a tecnologia avan\u00e7ada de irriga\u00e7\u00e3o pode melhorar a sustentabilidade e a efici\u00eancia em projetos de paisagismo urbano. O jardim n\u00e3o s\u00f3 melhorou esteticamente a paisagem urbana, como tamb\u00e9m contribuiu significativamente para a efici\u00eancia energ\u00e9tica do edif\u00edcio, consolidando-se como um marco na inova\u00e7\u00e3o do paisagismo urbano e na sustentabilidade ambiental.<\/p>\n<p>Gra\u00e7as \u00e0 tecnologia <a href=\"https:\/\/azud.com\/producto\/navia\/\" target=\"_blank\" rel=\"noopener\"><strong>AZUD NAVIA ND<\/strong><\/a> obteve-se:<\/p>\n<ul>\n<li><strong>Uniformidade da irriga\u00e7\u00e3o garantida a 100%:<\/strong> Cada planta recebe uma quantidade equilibrada de \u00e1gua e nutrientes, o que \u00e9 fundamental para o seu desenvolvimento saud\u00e1vel.<\/li>\n<li><strong>Melhor aproveitamento da \u00e1gua e dos nutrientes:<\/strong> O sistema garante uma distribui\u00e7\u00e3o eficiente, reduzindo o desperd\u00edcio e melhorando a absor\u00e7\u00e3o.<\/li>\n<li><strong>Elevada precis\u00e3o na rega:<\/strong> A tecnologia AZUD NAVIA ND permite um controlo rigoroso da rega, essencial para o sucesso da jardinagem vertical.<\/li>\n<li><strong>Tecnologia anti-drenagem:<\/strong> Ideal para jardins com diferen\u00e7as de n\u00edvel, mantendo a efic\u00e1cia do sistema de rega.<\/li>\n<\/ul>\n"},"tipo-de-industriacultivos":[],"subsector-casos-de-exito":[],"lineas-de-actividad-casos":[970],"soluciones-casos-de-exito":[1040],"sector-casos-de-exito":[1096],"class_list":["post-55718","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","lineas-de-actividad-casos-irrigacao","soluciones-casos-de-exito-riego-por-goteo","sector-casos-de-exito-paisagismo"],"_links":{"self":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"version-history":[{"count":1,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55718\/revisions"}],"predecessor-version":[{"id":74609,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55718\/revisions\/74609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media\/6699"}],"wp:attachment":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=55718"}],"wp:term":[{"taxonomy":"tipo-de-industriacultivos","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/tipo-de-industriacultivos?post=55718"},{"taxonomy":"subsector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/subsector-casos-de-exito?post=55718"},{"taxonomy":"lineas-de-actividad-casos","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/lineas-de-actividad-casos?post=55718"},{"taxonomy":"soluciones-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/soluciones-casos-de-exito?post=55718"},{"taxonomy":"sector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/sector-casos-de-exito?post=55718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}