{"id":55704,"date":"2025-05-29T12:31:04","date_gmt":"2025-05-29T12:31:04","guid":{"rendered":"https:\/\/azud.com\/casos-de-exito\/grandes-poupancas-no-consumo-de-agua-em-pomares-de-macieiras-biologicas-com-rgs-e-azud-premier\/"},"modified":"2026-07-07T10:51:58","modified_gmt":"2026-07-07T10:51:58","slug":"grandes-poupancas-no-consumo-de-agua-em-pomares-de-macieiras-biologicas-com-rgs-e-azud-premier","status":"publish","type":"caso-de-exito","link":"https:\/\/azud.com\/pt-pt\/casos-de-sucesso\/grandes-poupancas-no-consumo-de-agua-em-pomares-de-macieiras-biologicas-com-rgs-e-azud-premier\/","title":{"rendered":"Grande poupan\u00e7a no consumo de \u00e1gua no cultivo de ma\u00e7\u00e3s biol\u00f3gicas com o RGS e o AZUD PREMIER"},"featured_media":16693,"menu_order":0,"template":"","meta":{"compania_titulo_":"","compania_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/Soluciones-de-Riego-Por-Goteo-Subterraneo-en-cultivos-ecologicos_-manzana-ecologica-en-alta-densidad.mp4","compania_texto":"<p>Projeto em colabora\u00e7\u00e3o com uma grande empresa produtora e comercializadora de fruta, que se caracteriza pelo seu grande progresso, empenho e experi\u00eancia.<\/p>\n<p>A empresa est\u00e1 sempre em constante inova\u00e7\u00e3o e a enfrentar novos desafios com um objetivo: a vontade de melhorar a cada dia.<\/p>\n<hr \/>\n<p><strong>Localiza\u00e7\u00e3o<\/strong>: Lleida<\/p>\n","el_reto_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/imagen-02-NUFRI.webp","compania_texto_copy":"<p>Lan\u00e7aram um projeto inovador com a <strong>a maior propriedade de toda a Europa<\/strong> na produ\u00e7\u00e3o <strong>ma\u00e7\u00e3 biol\u00f3gica\/ecol\u00f3gica<\/strong>.<\/p>\n<p>A transi\u00e7\u00e3o para a agricultura biol\u00f3gica <strong>implica uma mudan\u00e7a na gest\u00e3o da cultura<\/strong>. A ado\u00e7\u00e3o de um sistema de densidade extremamente elevada, a restri\u00e7\u00e3o \u00e0 utiliza\u00e7\u00e3o de herbicidas e o facto de os tubos se encontrarem \u00e0 superf\u00edcie t\u00eam colocado desafios consider\u00e1veis neste processo.<\/p>\n<p>Al\u00e9m disso, a aplica\u00e7\u00e3o de nutri\u00e7\u00e3o org\u00e2nica \u00e9 muito mais complexa. Da mesma forma, procuravam ter uma pegada <strong>baixa hidrica<\/strong> na produ\u00e7\u00e3o de ma\u00e7\u00e3s. A quinta tinha certos <strong>desn\u00edveis<\/strong> e o projeto em si representava uma <strong>grande investimento<\/strong>, o que exigiria uma garantia.<\/p>\n","la_solucion_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/imagen-03-NUFRI.webp","la_solucion_texto":"<p>O <strong>Irriga\u00e7\u00e3o por gotejamento subsuperficial (SDI)<\/strong> dava-nos respostas e solu\u00e7\u00f5es para todos os problemas e desafios do projeto. Conseguimos reduzir a pegada h\u00eddrica e elimin\u00e1mos os tubos \u00e0 superf\u00edcie, gerindo a planta\u00e7\u00e3o sem obst\u00e1culos e sem pisar os tubos.<\/p>\n<p>Al\u00e9m disso, realizar a instala\u00e7\u00e3o e o projeto com <a href=\"https:\/\/azud.com\/producto\/azud-premier-pc-as\/\" target=\"_blank\" rel=\"noopener\"><strong>AZUD PREMIER<\/strong><\/a> com os seus grandes passos em forma de labirinto, embora tenha sido concebido para um caudal de 0,9 l\/h, temos a certeza de que <strong>funciona com total garantia contra obstru\u00e7\u00f5es e com nutri\u00e7\u00e3o org\u00e2nica<\/strong>.<\/p>\n<p>Por outro lado, \u00e9 utilizado um sistema de filtragem de discos <a href=\"https:\/\/azud.com\/producto\/azud-helix-automatic-4dcl-dlp\/\" target=\"_blank\" rel=\"noopener\"><strong>AZUD HELIX AUTOMATIC 4DCL DLP<\/strong><\/a>, que filtra tanto a \u00e1gua de rega como os nutrientes, para obter uma <strong>mistura mais homog\u00e9nea e de melhor qualidade<\/strong> adequada para funcionar com total garantia no sistema de rega.<\/p>\n","beneficios_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/imagen-04-NUFRI.webp","beneficios_texto":"<p>Oferecemos um <strong>servi\u00e7o orientado para a solu\u00e7\u00e3o<\/strong> e os requisitos deste tipo de cultivo biol\u00f3gico. Na AZUD, concebemos o <strong>projeto personalizado<\/strong> e prestamos um servi\u00e7o de aconselhamento sobre a gest\u00e3o e a manuten\u00e7\u00e3o. Foi concebido um equipamento espec\u00edfico para permitir a implementa\u00e7\u00e3o do RGS. <strong>AZUD PREMIER + AZUD HELIX AUTOMATIC 4DCL DLP<\/strong>.<\/p>\n<p><strong>Cultivo e variedade:<\/strong> Manzano (OPAL)<br \/>\n<strong>Marco Cultivo:<\/strong> 3,0 x 0,66 m<br \/>\n<strong>\u00c1rea:<\/strong> 40 hectares<br \/>\n<strong>Ano de instala\u00e7\u00e3o:<\/strong> 2020<br \/>\n<strong>Material instalado:<\/strong><\/p>\n<ul>\n<li>Descri\u00e7\u00e3o do material: PREMIER PC AS d20<\/li>\n<li>Caudal de los gotejadores: 0,9 l\/h<\/li>\n<li>Dist\u00e2ncia entre os gotejadores: 0,50 m<\/li>\n<li>Dist\u00e2ncia entre as linhas de gotejamento: Linha dupla a 30 cm do tronco<\/li>\n<li>Profundidade de enterramento: 25 cm<\/li>\n<\/ul>\n"},"tipo-de-industriacultivos":[872],"subsector-casos-de-exito":[945],"lineas-de-actividad-casos":[965,970],"soluciones-casos-de-exito":[1055],"sector-casos-de-exito":[1091],"class_list":["post-55704","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","tipo-de-industriacultivos-maca","subsector-casos-de-exito-lenhosos","lineas-de-actividad-casos-filtracao","lineas-de-actividad-casos-irrigacao","soluciones-casos-de-exito-riego-por-goteo-subterraneo","sector-casos-de-exito-agricultura-pt"],"_links":{"self":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"version-history":[{"count":1,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55704\/revisions"}],"predecessor-version":[{"id":74815,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/caso-de-exito\/55704\/revisions\/74815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media\/16693"}],"wp:attachment":[{"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=55704"}],"wp:term":[{"taxonomy":"tipo-de-industriacultivos","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/tipo-de-industriacultivos?post=55704"},{"taxonomy":"subsector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/subsector-casos-de-exito?post=55704"},{"taxonomy":"lineas-de-actividad-casos","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/lineas-de-actividad-casos?post=55704"},{"taxonomy":"soluciones-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/soluciones-casos-de-exito?post=55704"},{"taxonomy":"sector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/pt-pt\/wp-json\/wp\/v2\/sector-casos-de-exito?post=55704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}