{"id":1051,"count":5,"description":"","link":"https:\/\/azud.com\/it\/soluciones-casos-de-exito\/digitalizacion-del-riego\/","name":"Digitalizzazione dell&#039;irrigazione","slug":"digitalizacion-del-riego","taxonomy":"soluciones-casos-de-exito","meta":[],"_links":{"self":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/soluciones-casos-de-exito\/1051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/soluciones-casos-de-exito"}],"about":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/taxonomies\/soluciones-casos-de-exito"}],"wp:post_type":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito?soluciones-casos-de-exito=1051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}