{"id":1036,"count":28,"description":"","link":"https:\/\/azud.com\/it\/soluciones-casos-de-exito\/filtracion-de-aguas-de-riego\/","name":"Filtrazione delle acque di irrigazione","slug":"filtracion-de-aguas-de-riego","taxonomy":"soluciones-casos-de-exito","meta":[],"_links":{"self":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/soluciones-casos-de-exito\/1036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/soluciones-casos-de-exito"}],"about":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/taxonomies\/soluciones-casos-de-exito"}],"wp:post_type":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito?soluciones-casos-de-exito=1036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}