{"id":64907,"date":"2025-07-03T15:45:55","date_gmt":"2025-07-03T15:45:55","guid":{"rendered":"https:\/\/azud.com\/productos\/azud-fit-plus-2\/"},"modified":"2026-07-03T05:15:40","modified_gmt":"2026-07-03T05:15:40","slug":"azud-fit-plus-2","status":"publish","type":"productos","link":"https:\/\/azud.com\/it\/productos\/azud-fit-plus-2\/","title":{"rendered":"AZUD FIT PLUS"},"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"nombre":"AZUD FIT PLUS","descripcion":"Raccordi di sicurezza a spillo per tubi di irrigazione spessi (0,9 - 1,2 mm \/ 35 - 47 mil)","fotos":["https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/AZUD_FIT_PLUS_con_logos-2.webp","https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/AZUD_FIT_PLUS-5.webp","https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/conexiC3B3n_AZUD_FIT_PLUS-3.webp","https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/tapon_en_tuberia_AZUD_FIT_PLUS-2.webp"],"video_producto":"","referencia_de_producto":"16Z1","identificador_unico":"16Z1it","productos_relacionados":"25Z1,26Z1,28Z11,16Z2,24Z1,01Z1","etiqueta-producto":["accesorios-de-conexion"],"caracteristicas_tecnicas":"Raccordo di sicurezza<br \/>\r\nAcetale<br \/>\r\nTubo caldo<br \/>\r\n\u00d816, \u00d820<br \/>\r\n0,9 - 1,2 mm \/ 35 - 47 mil","ideal_para":"","destacado":"Raccordo di sicurezza<br \/>\r\nAcetale<br \/>\r\nTubo caldo<br \/>\r\n\u00d816, \u00d820<br \/>\r\n0,9 - 1,2 mm \/ 35 - 47 mil","valores_diferenciales":[{"icono":"https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/icono_Seguridad_02-4.webp","titulo":"Sicurezza","contenido":"<p>Chiusura robusta e sicura senza distacchi.<\/p><p>Garantisce una tenuta stagna, prevenendo perdite.<\/p>"},{"icono":"https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/icono_Ahorro_02-1.webp","titulo":"Risparmio","contenido":"<p>Progettato per un facile inserimento del raccordo nel tubo.<\/p><p>Installazione rapida, con conseguente riduzione dei tempi e della manodopera necessari.<\/p>"},{"icono":"https:\/\/azud.com\/wp-content\/uploads\/2025\/07\/icono_Durabilidad_02-3.webp","titulo":"Durabilit\u00e0","contenido":"<p>Elevata resistenza meccanica anche in condizioni di lavoro estreme, testata in laboratorio e con 5 anni di garanzia.<\/p><p>Protezione dai raggi UV e resistenza ai prodotti chimici per l'irrigazione.<\/p>"}],"apps":"","hoja_tecnica_1_url":"http:\/\/d7rh5s3nxmpy4.cloudfront.net\/CMP6738\/files\/AZUD_FIT_PLUS-ENG.pdf","hoja_tecnica_1_nombre":"Scheda tecnica AZUD FIT PLUS","descargas_miniatura1":"","hoja_tecnica_2_nombre":"","descargas_miniatura2":"","hoja_tecnica_2_url":"","descargas-tipodedocumento2":"","descargas_tipo_de_documento":"","productos_filtro":"Riego","productos_riego":"Accesorios de conexi\u00f3n","productos_tipo_de_tuberia":"","productos_autocompensacion":"","productos_ciclo_de_vida_del_cultivo":"","productos_filtracion":"","productos_tecnologia_de_filtracion":"","productos_material":"","_wpml_import_language_code":"","_wpml_import_source_language_code":"","_wpml_import_translation_group":"","orden-producto":"33","visible":[]},"class_list":["post-64907","productos","type-productos","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/productos\/64907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/productos"}],"about":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/types\/productos"}],"version-history":[{"count":0,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/productos\/64907\/revisions"}],"wp:attachment":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/media?parent=64907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}