{"id":56259,"date":"2023-04-21T10:01:34","date_gmt":"2023-04-21T10:01:34","guid":{"rendered":"https:\/\/azud.com\/casos-de-exito\/pisa-pharmaceuticals-ottimizza-il-funzionamento-dei-suoi-letti-di-pirolusite\/"},"modified":"2026-07-07T11:09:20","modified_gmt":"2026-07-07T11:09:20","slug":"pisa-pharmaceuticals-ottimizza-il-funzionamento-dei-suoi-letti-di-pirolusite","status":"publish","type":"caso-de-exito","link":"https:\/\/azud.com\/it\/storie-di-successo\/pisa-pharmaceuticals-ottimizza-il-funzionamento-dei-suoi-letti-di-pirolusite\/","title":{"rendered":"Farmac\u00e9utica PISA ottimizza il funzionamento dei propri letti di pirolusite."},"featured_media":73835,"menu_order":0,"template":"","meta":{"compania_titulo_":"PISA","compania_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2026\/07\/Referencias-PISA-1.webp","compania_texto":"<ul>\n<li><strong>Paese<\/strong>: Messico<\/li>\n<li><strong>Settore di attivit\u00e0<\/strong>: Industria chimica<\/li>\n<li><strong>Utente finale<\/strong>: PISA<\/li>\n<li><strong>Applicazione<\/strong>: Protezione dei mezzi filtranti<\/li>\n<li><strong>Prodotto<\/strong>: AZUD HELIX AUTOMATIC FT200 AA DLP INDUSTRIALE<\/li>\n<li><strong>Portata (m<sup>3<\/sup>\/h)<\/strong>: 600<\/li>\n<\/ul>\n","el_reto_imagen":"","compania_texto_copy":"","la_solucion_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2026\/07\/Referencias-PISA-1.webp","la_solucion_texto":"<p>PISA riduce la propria impronta idrica diminuendo del 90% le operazioni di pulizia dei letti di pirolusite nei propri bacini di captazione.<\/p>\n","beneficios_imagen":"","beneficios_texto":""},"tipo-de-industriacultivos":[808],"subsector-casos-de-exito":[926],"lineas-de-actividad-casos":[966],"soluciones-casos-de-exito":[1186],"sector-casos-de-exito":[1072],"class_list":["post-56259","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","tipo-de-industriacultivos-quimica-y-farmaceutica","subsector-casos-de-exito-industria-chimica-e-farmaceutica","lineas-de-actividad-casos-filtrazione","soluciones-casos-de-exito-protezione-dei-mezzi-filtranti","sector-casos-de-exito-industriale"],"_links":{"self":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"version-history":[{"count":1,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56259\/revisions"}],"predecessor-version":[{"id":74975,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56259\/revisions\/74975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/media\/73835"}],"wp:attachment":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/media?parent=56259"}],"wp:term":[{"taxonomy":"tipo-de-industriacultivos","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/tipo-de-industriacultivos?post=56259"},{"taxonomy":"subsector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/subsector-casos-de-exito?post=56259"},{"taxonomy":"lineas-de-actividad-casos","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/lineas-de-actividad-casos?post=56259"},{"taxonomy":"soluciones-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/soluciones-casos-de-exito?post=56259"},{"taxonomy":"sector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/sector-casos-de-exito?post=56259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}