{"id":56233,"date":"2023-04-27T09:08:43","date_gmt":"2023-04-27T09:08:43","guid":{"rendered":"https:\/\/azud.com\/casos-de-exito\/somacyl-rigenerera-le-acque-reflue-utilizzando-la-pre-filtrazione-per-proteggere-il-settore-terziario\/"},"modified":"2026-07-07T11:09:01","modified_gmt":"2026-07-07T11:09:01","slug":"somacyl-rigenerera-le-acque-reflue-utilizzando-la-pre-filtrazione-per-proteggere-il-settore-terziario","status":"publish","type":"caso-de-exito","link":"https:\/\/azud.com\/it\/storie-di-successo\/somacyl-rigenerera-le-acque-reflue-utilizzando-la-pre-filtrazione-per-proteggere-il-settore-terziario\/","title":{"rendered":"SOMACYL rigenerer\u00e0 le acque reflue ricorrendo alla prefiltrazione per proteggere il trattamento terziario"},"featured_media":54968,"menu_order":0,"template":"","meta":{"compania_titulo_":"SOMACYL","compania_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/10\/Referencias-Somacyl-1.webp","compania_texto":"<ul>\n<li><strong>Paese<\/strong>: Spagna<\/li>\n<li><strong>Settore di attivit\u00e0<\/strong>: Industria alimentare<\/li>\n<li><strong>Utente finale<\/strong>: SOMACYL<\/li>\n<li><strong>Applicazione<\/strong>: Trattamento delle acque reflue<\/li>\n<li><strong>Prodotto<\/strong>: AZUD HELIX AUTOMATIC FT200 DLP INDUSTRIALE<\/li>\n<li><strong>Portata (m<sup>3<\/sup>\/h)<\/strong>: 15<\/li>\n<\/ul>\n<p>SOMACYL protegge, tramite la filtrazione ad anelli, le membrane di ultrafiltrazione e di osmosi inversa nell'impianto di rigenerazione delle acque reflue trattate provenienti dagli essiccatoi di prosciutti.<\/p>\n","el_reto_imagen":"","compania_texto_copy":"","la_solucion_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/10\/Referencias-Somacyl-1.webp","la_solucion_texto":"<p>SOMACYL rigenerer\u00e0 le acque reflue trattate del nuovo impianto di depurazione comunale ad alta salinit\u00e0, proteggendo il sistema di depurazione terziario tramite prefiltrazione<\/p>\n","beneficios_imagen":"","beneficios_texto":""},"tipo-de-industriacultivos":[],"subsector-casos-de-exito":[],"lineas-de-actividad-casos":[961],"soluciones-casos-de-exito":[1031],"sector-casos-de-exito":[1082],"class_list":["post-56233","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","lineas-de-actividad-casos-trattamento_delle_acque","soluciones-casos-de-exito-regeneracion-de-aguas-residuales","sector-casos-de-exito-comunale"],"_links":{"self":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"version-history":[{"count":1,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56233\/revisions"}],"predecessor-version":[{"id":74953,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56233\/revisions\/74953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/media\/54968"}],"wp:attachment":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/media?parent=56233"}],"wp:term":[{"taxonomy":"tipo-de-industriacultivos","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/tipo-de-industriacultivos?post=56233"},{"taxonomy":"subsector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/subsector-casos-de-exito?post=56233"},{"taxonomy":"lineas-de-actividad-casos","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/lineas-de-actividad-casos?post=56233"},{"taxonomy":"soluciones-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/soluciones-casos-de-exito?post=56233"},{"taxonomy":"sector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/sector-casos-de-exito?post=56233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}