{"id":56196,"date":"2023-06-16T11:02:03","date_gmt":"2023-06-16T11:02:03","guid":{"rendered":"https:\/\/azud.com\/casos-de-exito\/finsa-installa-un-sistema-di-trattamento-delle-acque-reflue-mbbr-in-container-in-una-zona-industriale-di-monterrey\/"},"modified":"2026-07-07T11:08:07","modified_gmt":"2026-07-07T11:08:07","slug":"finsa-installa-un-sistema-di-trattamento-delle-acque-reflue-mbbr-in-container-in-una-zona-industriale-di-monterrey","status":"publish","type":"caso-de-exito","link":"https:\/\/azud.com\/it\/storie-di-successo\/finsa-installa-un-sistema-di-trattamento-delle-acque-reflue-mbbr-in-container-in-una-zona-industriale-di-monterrey\/","title":{"rendered":"FINSA installa un sistema di depurazione MBBR in container in una zona industriale di Monterrey"},"featured_media":55190,"menu_order":0,"template":"","meta":{"compania_titulo_":"FINSA","compania_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/10\/Referencias-FINSA-1.webp","compania_texto":"<ul>\n<li><strong>Paese<\/strong>: Spagna<\/li>\n<li><strong>Settore di attivit\u00e0<\/strong>: Comunale<\/li>\n<li><strong>Utente finale<\/strong>: Villas Coco de mar<\/li>\n<li><strong>Applicazione<\/strong>: Trattamento decentralizzato delle acque reflue<\/li>\n<li><strong>Prodotto<\/strong>: AZUD WATERTECH WW INDUSTRIAL<\/li>\n<li><strong>Portata (m<sup>3<\/sup>\/d)<\/strong>: 300<\/li>\n<\/ul>\n","el_reto_imagen":"","compania_texto_copy":"","la_solucion_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/10\/Referencias-FINSA-1.webp","la_solucion_texto":"","beneficios_imagen":"","beneficios_texto":""},"tipo-de-industriacultivos":[],"subsector-casos-de-exito":[],"lineas-de-actividad-casos":[961],"soluciones-casos-de-exito":[1006],"sector-casos-de-exito":[1082],"class_list":["post-56196","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","lineas-de-actividad-casos-trattamento_delle_acque","soluciones-casos-de-exito-trattamento_decentralizzato_delle_acque_reflue","sector-casos-de-exito-comunale"],"_links":{"self":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"version-history":[{"count":1,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56196\/revisions"}],"predecessor-version":[{"id":74918,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56196\/revisions\/74918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/media\/55190"}],"wp:attachment":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/media?parent=56196"}],"wp:term":[{"taxonomy":"tipo-de-industriacultivos","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/tipo-de-industriacultivos?post=56196"},{"taxonomy":"subsector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/subsector-casos-de-exito?post=56196"},{"taxonomy":"lineas-de-actividad-casos","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/lineas-de-actividad-casos?post=56196"},{"taxonomy":"soluciones-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/soluciones-casos-de-exito?post=56196"},{"taxonomy":"sector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/sector-casos-de-exito?post=56196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}