{"id":56063,"date":"2025-05-28T12:40:34","date_gmt":"2025-05-28T12:40:34","guid":{"rendered":"https:\/\/azud.com\/casos-de-exito\/innovazione-idrica-nellindustria-alimentare-in-uruguay\/"},"modified":"2026-07-07T11:28:35","modified_gmt":"2026-07-07T11:28:35","slug":"innovazione-idrica-nellindustria-alimentare-in-uruguay","status":"publish","type":"caso-de-exito","link":"https:\/\/azud.com\/it\/storie-di-successo\/innovazione-idrica-nellindustria-alimentare-in-uruguay\/","title":{"rendered":"Innovazione nel settore idrico nell&#8217;industria alimentare in Uruguay"},"featured_media":56064,"menu_order":0,"template":"","meta":{"compania_titulo_":"Industria alimentare","compania_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/dubai_referencia-1-scaled-1.webp","compania_texto":"<p>Una delle principali aziende al mondo nel settore della carne bovina deve affrontare la sfida costante di conciliare la crescita sostenibile con l'efficienza operativa.<\/p>\n<hr \/>\n<p><strong>Posizione<\/strong>: Emirati Arabi Uniti<br \/>\n<strong>Settore di attivit\u00e0<\/strong>: Comunale<br \/>\n<strong>Utente finale<\/strong>: Hotel<br \/>\n<strong>Applicazione<\/strong>: Riutilizzo delle acque grigie<br \/>\n<strong>Prodotto<\/strong>: AZUD WATERTECH GW INDUSTRIAL<br \/>\n<strong>Portata (m<sup>3<\/sup>\/d)<\/strong>: 100<\/p>\n","el_reto_imagen":"","compania_texto_copy":"","la_solucion_imagen":"","la_solucion_texto":"","beneficios_imagen":"","beneficios_texto":""},"tipo-de-industriacultivos":[813],"subsector-casos-de-exito":[931],"lineas-de-actividad-casos":[961],"soluciones-casos-de-exito":[986],"sector-casos-de-exito":[1072],"class_list":["post-56063","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","tipo-de-industriacultivos-agroalimentare","subsector-casos-de-exito-settore-agroalimentare","lineas-de-actividad-casos-trattamento_delle_acque","soluciones-casos-de-exito-reutilizacion-de-aguas-grises","sector-casos-de-exito-industriale"],"_links":{"self":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"version-history":[{"count":1,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56063\/revisions"}],"predecessor-version":[{"id":75043,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/caso-de-exito\/56063\/revisions\/75043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/media\/56064"}],"wp:attachment":[{"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/media?parent=56063"}],"wp:term":[{"taxonomy":"tipo-de-industriacultivos","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/tipo-de-industriacultivos?post=56063"},{"taxonomy":"subsector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/subsector-casos-de-exito?post=56063"},{"taxonomy":"lineas-de-actividad-casos","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/lineas-de-actividad-casos?post=56063"},{"taxonomy":"soluciones-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/soluciones-casos-de-exito?post=56063"},{"taxonomy":"sector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/it\/wp-json\/wp\/v2\/sector-casos-de-exito?post=56063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}