{"id":17697,"date":"2025-05-23T11:14:39","date_gmt":"2025-05-23T11:14:39","guid":{"rendered":"https:\/\/azud.com\/casos-de-exito\/agriculture-numerique-pour-ameliorer-la-sante-de-la-culture-des-mandariniers\/"},"modified":"2026-07-07T05:44:38","modified_gmt":"2026-07-07T05:44:38","slug":"agriculture-numerique-pour-ameliorer-la-sante-de-la-culture-des-mandariniers","status":"publish","type":"caso-de-exito","link":"https:\/\/azud.com\/fr\/etudes-de-cas\/agriculture-numerique-pour-ameliorer-la-sante-de-la-culture-des-mandariniers\/","title":{"rendered":"Gestion num\u00e9rique dans l&rsquo;agriculture pour am\u00e9liorer la sant\u00e9 des cultures de mandarines"},"featured_media":7059,"menu_order":0,"template":"","meta":{"compania_titulo_":"La culture de la mandarine \u00e0 Castell\u00f3n","compania_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/iStock-1250899105-1-1.webp","compania_texto":"<p>Cette propri\u00e9t\u00e9 est situ\u00e9e \u00e0 Castell\u00f3n, \u00e0 l'est de <strong>Espagne<\/strong>, d'une surface de <strong>20 hectares<\/strong> d\u00e9di\u00e9es \u00e0 la culture de <strong>mandarine<\/strong> en culture intensive avec la vari\u00e9t\u00e9 Orri.<\/p>\n<p>Dans cette \u00e9tude de cas, notre client \u00e9tait un conseiller agronomique qui travaillait dans plusieurs exploitations d'agrumiculteurs de la r\u00e9gion.<\/p>\n<hr \/>\n<p><strong>Localisation<\/strong>: Castell\u00f3n<br \/>\n<strong>Culture<\/strong>: Mandarine<\/p>\n","el_reto_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/Frame-23-1-1.webp","compania_texto_copy":"<p>Cette propri\u00e9t\u00e9 pr\u00e9sentait notamment <strong>probl\u00e8mes d'asphyxie racinaire<\/strong> dans les arbres en raison d'une accumulation d'eau \u00e0 la profondeur au printemps et en \u00e9t\u00e9, ce qui nuisait \u00e0 la sant\u00e9 des cultures, en particulier celle des mandarines de la vari\u00e9t\u00e9 Orri.<\/p>\n<p>Le principal d\u00e9fi consistait \u00e0 r\u00e9soudre le probl\u00e8me d'asphyxie racinaire caus\u00e9 par un arrosage traditionnel et excessif, ainsi que par le sol argileux de l'exploitation, situ\u00e9e \u00e0 proximit\u00e9 d'un cours d'eau saisonnier.<\/p>\n<p>Les sympt\u00f4mes observ\u00e9s sur les arbres, tels que des feuilles petites, un jaunissement et une d\u00e9foliation, indiquaient la n\u00e9cessit\u00e9 de <strong>retrouver la sant\u00e9<\/strong> de la plantation.<\/p>\n","la_solucion_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/Frame-22-2-1.webp","la_solucion_texto":"<p>La solution a consist\u00e9 \u00e0 am\u00e9liorer les pratiques d'irrigation afin de r\u00e9soudre ces probl\u00e8mes et d'am\u00e9liorer la sant\u00e9 des cultures, gr\u00e2ce \u00e0 la mise en \u0153uvre de technologies de pointe.<\/p>\n<p>On a utilis\u00e9 une <strong>station de surveillance \u00e9quip\u00e9e d'un capteur de temp\u00e9rature, d'un capteur d'humidit\u00e9 ambiante et d'un pluviom\u00e8tre permettant de suivre de mani\u00e8re tr\u00e8s localis\u00e9e l'\u00e9volution des temp\u00e9ratures et des pr\u00e9cipitations.<\/strong><\/p>\n<p>De plus, une <strong>sonde d'humidit\u00e9 capacitive de 90 cm de long<\/strong> pour surveiller l'humidit\u00e9 volum\u00e9trique du sol tout au long du profil. Cette sonde a \u00e9galement fourni des informations sur la conductivit\u00e9 \u00e9lectrique du sol et la temp\u00e9rature \u00e0 diff\u00e9rentes profondeurs.<\/p>\n<p>L'approche adopt\u00e9e par les techniciens a consist\u00e9 \u00e0 ajuster la fr\u00e9quence et la dur\u00e9e d'irrigation en fonction du comportement de l'eau dans le profil de sol de 90 cm, o\u00f9 se trouvaient les racines des mandariniers. De plus, les p\u00e9riodes de pr\u00e9-fertilisation, de fertilisation et de post-fertilisation ont \u00e9t\u00e9 ajust\u00e9es \u00e0 partir des donn\u00e9es relatives \u00e0 la conductivit\u00e9 \u00e9lectrique du sol, en veillant \u00e0 maintenir des valeurs optimales pour la sant\u00e9 de la culture.<\/p>\n<p>La temp\u00e9rature du sol et les donn\u00e9es m\u00e9t\u00e9orologiques ont \u00e9galement \u00e9t\u00e9 utilis\u00e9es pour d\u00e9terminer le moment le plus appropri\u00e9 pour commencer l'arrosage et la fertilisation, en r\u00e9pondant en temps r\u00e9el aux besoins de la plante.<\/p>\n","beneficios_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/05\/Frame-21-2-1-1.webp","beneficios_texto":"<p>La mise en \u0153uvre de cette solution d'irrigation efficace gr\u00e2ce \u00e0 la gestion num\u00e9rique a apport\u00e9 une s\u00e9rie d'avantages durables en l'espace d'un an :<\/p>\n<ul>\n<li><strong>Disparition des maladies fongiques et des sympt\u00f4mes d'asphyxie racinaire<\/strong>, ce qui permet d'\u00e9viter la percolation \u00e0 la profondeur et d'am\u00e9liorer la sant\u00e9 des cultures.<\/li>\n<li><strong>R\u00e9duction de la consommation d'eau d'irrigation, de gazole (\u00e9nergie) et d'engrais<\/strong>. On est pass\u00e9 d'un arrosage de 2 heures, 6 jours par semaine, \u00e0 un arrosage d'une heure, 4 jours par semaine, ce qui a permis d'optimiser l'utilisation des ressources.<\/li>\n<li><strong>Am\u00e9lioration de l'assimilation des nutriments<\/strong>, ce qui a permis d'\u00e9viter la lixiviation et le blocage des ions, contribuant ainsi \u00e0 un meilleur d\u00e9veloppement des arbres ainsi qu'\u00e0 une production plus importante et \u00e0 un calibre sup\u00e9rieur des mandarines.<\/li>\n<\/ul>\n"},"tipo-de-industriacultivos":[1148],"subsector-casos-de-exito":[943],"lineas-de-actividad-casos":[978],"soluciones-casos-de-exito":[1048],"sector-casos-de-exito":[1089],"class_list":["post-17697","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","tipo-de-industriacultivos-agrumes","subsector-casos-de-exito-ligneux","lineas-de-actividad-casos-automatisation-et-gestion-numerique","soluciones-casos-de-exito-digitalizacion-del-riego","sector-casos-de-exito-agriculture-fr"],"_links":{"self":[{"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/caso-de-exito\/17697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"version-history":[{"count":1,"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/caso-de-exito\/17697\/revisions"}],"predecessor-version":[{"id":74405,"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/caso-de-exito\/17697\/revisions\/74405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/media\/7059"}],"wp:attachment":[{"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/media?parent=17697"}],"wp:term":[{"taxonomy":"tipo-de-industriacultivos","embeddable":true,"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/tipo-de-industriacultivos?post=17697"},{"taxonomy":"subsector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/subsector-casos-de-exito?post=17697"},{"taxonomy":"lineas-de-actividad-casos","embeddable":true,"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/lineas-de-actividad-casos?post=17697"},{"taxonomy":"soluciones-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/soluciones-casos-de-exito?post=17697"},{"taxonomy":"sector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/fr\/wp-json\/wp\/v2\/sector-casos-de-exito?post=17697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}