{"id":1013,"count":5,"description":"","link":"https:\/\/azud.com\/de\/soluciones-casos-de-exito\/potabilizacion-movil-de-aguas\/","name":"Mobile Wasseraufbereitung","slug":"potabilizacion-movil-de-aguas","taxonomy":"soluciones-casos-de-exito","meta":[],"_links":{"self":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/soluciones-casos-de-exito\/1013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/soluciones-casos-de-exito"}],"about":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/taxonomies\/soluciones-casos-de-exito"}],"wp:post_type":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/caso-de-exito?soluciones-casos-de-exito=1013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}