{"id":53671,"date":"2023-10-17T13:19:28","date_gmt":"2023-10-17T13:19:28","guid":{"rendered":"https:\/\/azud.com\/blog\/wiederverwendung-von-grauwasser-der-weg-zu-nachhaltigkeit-und-leed-zertifizierung\/"},"modified":"2026-07-08T12:02:40","modified_gmt":"2026-07-08T12:02:40","slug":"wiederverwendung-von-grauwasser-der-weg-zu-nachhaltigkeit-und-leed-zertifizierung","status":"publish","type":"post","link":"https:\/\/azud.com\/de\/blog\/wiederverwendung-von-grauwasser-der-weg-zu-nachhaltigkeit-und-leed-zertifizierung\/","title":{"rendered":"Wiederverwendung von Grauwasser: Der Weg zu Nachhaltigkeit und zur LEED-Zertifizierung"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">In einer Welt, in der ein verantwortungsvoller Umgang mit Wasser f\u00fcr die Bew\u00e4ltigung von Umwelt- und Ressourcenproblemen unerl\u00e4sslich ist, erweist sich die Wiederverwendung von Grauwasser als innovative und nachhaltige L\u00f6sung.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Was versteht man unter Grauwasser?<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Grauwasser stammt aus Waschbecken, Duschen und Bidets und zeichnet sich dadurch aus, dass es im Vergleich zu Schwarzwasser, das aus Toiletten stammt und F\u00e4kalien enth\u00e4lt, eine deutlich geringere organische Belastung aufweist. Aufgrund ihres geringeren Verschmutzungsgrades l\u00e4sst es sich viel einfacher f\u00fcr die sp\u00e4tere Wiederverwendung aufbereiten, was im Vergleich zur Abwasserbehandlung eine effizientere Nutzung von Ressourcen bedeutet.<\/p>\n\n<p class=\"wp-block-paragraph\">Sch\u00e4tzungen zufolge entfallen etwa 75 % des in Haushalten und Hotels anfallenden Abwassers auf Grauwasser, wobei der Durchschnittsverbrauch zwischen 50 und 100 Litern pro Person und Tag liegt, was dessen Potenzial als wertvolle Ressource unterstreicht.<\/p>\n\n<h2 class=\"wp-block-heading\">Grauwasser-Wiederverwertungsanlage: AZUD WATERTECH GW<\/h2>\n\n<figure class=\"wp-block-image aligncenter\"><a href=\"https:\/\/azudindustrial.com\/producto\/AZUD WATERTECH GW\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/azudindustrial.com\/wp-content\/uploads\/2023\/02\/reutilizacion-aguas-grises-3.webp\" alt=\"\" class=\"wp-image-9404\"\/><\/a><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Um diese Herausforderung zu bew\u00e4ltigen, pr\u00e4sentiert AZUD eine effektive L\u00f6sung: die Grauwasseraufbereitungsanlage <a href=\"https:\/\/azudindustrial.com\/producto\/azud-watertech-gw\/\" target=\"_blank\" rel=\"noopener\"><strong>AZUD WATERTECH GW<\/strong><\/a>. Diese Anlage nutzt verschiedene Technologien, die zusammen eine hochwertige Filterung gew\u00e4hrleisten und zur L\u00f6sung dieses Problems beitragen.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Scheibenfilterung.<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Filteranlage mit Scheibentechnologie und luftunterst\u00fctztem Selbstreinigungssystem <a href=\"https:\/\/azudindustrial.com\/producto\/azud-helix-automatic-ft200-aa-dlp\/\" target=\"_blank\" rel=\"noopener\">HELIX AUTOMATIC AA-Wehr<\/a>. Ein hocheffizientes Verfahren mit sehr geringem Wasser- und Energieverbrauch zur Entfernung anorganischer und organischer Schwebstoffe, das zudem die nachgeschalteten Anlagen und Membranen sch\u00fctzt.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"767\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2024\/12\/FT_AA.webp\" alt=\"\" class=\"wp-image-74061\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Filtration mittels Ultrafiltrationsmembranen.<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Die Ultrafiltrations-Membrantechnologie gew\u00e4hrleistet die Qualit\u00e4t des aufbereiteten Wassers, indem sie unangenehme Ger\u00fcche beseitigt, die Schlammbildung verhindert und st\u00f6rende Ger\u00e4usche reduziert.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Desinfektion.<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Dosierung von Oxidationsmitteln zur Entfernung organischer Stoffe. Dar\u00fcber hinaus besteht die M\u00f6glichkeit, Hypochlorit zu dosieren oder UV-Lampen einzusetzen, um die Desinfektion des Wassers zu gew\u00e4hrleisten.<\/p>\n\n<p class=\"wp-block-paragraph\">Diese Anlagen sind kompakt und modular aufgebaut, was ihre Installation an schwer zug\u00e4nglichen Stellen sowie ihren sp\u00e4teren Betrieb erleichtert.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Erfolgsbeispiele f\u00fcr die Wiederverwendung von st\u00e4dtischem Grauwasser<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Diese Systeme zur Wiederverwendung und Aufbereitung von Grauwasser <a href=\"https:\/\/azudindustrial.com\/producto\/azud-watertech-gw\/\" target=\"_blank\" rel=\"noopener\"><strong>AZUD WATERTECH GW<\/strong><\/a> wurden weltweit eingef\u00fchrt. Zu den bemerkenswerten Beispielen z\u00e4hlen <strong>Hotels<\/strong> wo sie zur Bew\u00e4sserung ihrer G\u00e4rten wiederverwendet werden und <strong>B\u00fcrogeb\u00e4ude<\/strong> die ihren \u00f6kologischen Fu\u00dfabdruck verringern, indem sie Grauwasser f\u00fcr die Sp\u00fclk\u00e4sten der Toiletten wiederverwenden.<\/p>\n\n<h3 class=\"wp-block-heading\">Wiederverwendung von Grauwasser in B\u00fcrogeb\u00e4uden: Synergie<\/h3>\n\n<p class=\"wp-block-paragraph\">Ein aktuelles Projekt, das besondere Beachtung verdient, befindet sich in Montevideo und wurde f\u00fcr das uruguayische Unternehmen SINERGIA durchgef\u00fchrt, das sich mit <strong>Vermietung von Gemeinschaftsb\u00fcros und flexiblen B\u00fcror\u00e4umen<\/strong>. In einem seiner herausragendsten Geb\u00e4ude, das Coworking-Pl\u00e4tze f\u00fcr mehr als 200 Personen bietet und \u00fcber Restaurants sowie Unterhaltungsbereiche verf\u00fcgt, wurde eine Anlage zur Wiederverwendung von Grauwasser und Regenwasser eingerichtet. Diese Ma\u00dfnahme hat es erm\u00f6glicht, das Wasser in den Toilettensp\u00fclk\u00e4sten wiederzuverwenden, wodurch eine <strong>eine erhebliche Einsparung von bis zu 30.000 Litern Trinkwasser pro Tag<\/strong>.<\/p>\n\n<p class=\"wp-block-paragraph\">Dies hat dazu beigetragen, SINERGIA als eines der nachhaltigsten Geb\u00e4ude Uruguays zu etablieren, da es <strong>die <a href=\"https:\/\/es.wikipedia.org\/wiki\/Liderazgo_en_Energ%C3%ADa_y_Dise%C3%B1o_Ambiental\" target=\"_blank\" rel=\"noopener\">LEED-Platin-Zertifizierung \u201eCore &amp; Shell\u201c<\/a><\/strong>, was belegt, dass das Geb\u00e4ude so errichtet wurde und betrieben wird, dass die Auswirkungen auf die Umwelt so gering wie m\u00f6glich sind.<\/p>\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" width=\"699\" height=\"297\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2023\/10\/coworking-sinergia.webp\" alt=\"Wiederverwendung von Grauwasser im Synergie-Geb&#xE4;ude in Montevideo\" class=\"wp-image-13533\" srcset=\"https:\/\/azud.com\/wp-content\/uploads\/2023\/10\/coworking-sinergia.webp 699w, https:\/\/azud.com\/wp-content\/uploads\/2023\/10\/coworking-sinergia-300x127.webp 300w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\">LEED-Zertifizierung<\/h3>\n\n<p class=\"wp-block-paragraph\">Die <strong>LEED-Zertifizierung (Excellence in Energy and Environmental Design) Platin \u201eCore &amp; Shell\u201c<\/strong> Es handelt sich um eine sehr hohe Zertifizierungsstufe, die vom USGBC (U.S. Green Building Council) f\u00fcr nachhaltige Bauprojekte im Rahmen des LEED-Zertifizierungssystems (Leadership in Energy and Environmental Design) vergeben wird. Die LEED-Zertifizierung dient der Bewertung und Anerkennung von Geb\u00e4uden und Projekten, bei denen nachhaltige und umweltfreundliche Praktiken umgesetzt wurden.<\/p>\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/azud.com\/wp-content\/uploads\/2023\/10\/LEED-150x150.webp\" alt=\"LEED-Zertifizierung (Excellence in Energy and Environmental Design) Platin &#x201E;Core &amp; Shell&#x201C; \" class=\"wp-image-13537\" srcset=\"https:\/\/azud.com\/wp-content\/uploads\/2023\/10\/LEED-150x150.webp 150w, https:\/\/azud.com\/wp-content\/uploads\/2023\/10\/LEED.webp 167w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Das Beispiel des SINERGIA-Geb\u00e4udes verdeutlicht eindrucksvoll, wie die Wiederverwendung von Grauwasser die Nachhaltigkeit von Geb\u00e4uden und Unternehmen ver\u00e4ndern kann. Dies senkt nicht nur den Trinkwasserverbrauch, sondern tr\u00e4gt auch erheblich zur Ressourcenschonung und zur Verringerung des \u00f6kologischen Fu\u00dfabdrucks bei.<\/p>\n\n<p class=\"wp-block-paragraph\">Wenn Sie mehr \u00fcber unsere L\u00f6sungen zur Wiederverwendung von st\u00e4dtischem Grauwasser erfahren m\u00f6chten <a href=\"https:\/\/azudindustrial.com\/contacto\/\" target=\"_blank\" rel=\"noopener\">Nehmen Sie Kontakt mit AZUD auf<\/a>. Unser Expertenteam wird Ihren Fall pr\u00fcfen, um Ihnen die L\u00f6sung anzubieten, die Ihren Bed\u00fcrfnissen am besten entspricht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In einer Welt, in der ein verantwortungsvoller Umgang mit Wasser f\u00fcr die Bew\u00e4ltigung von Umwelt- und Ressourcenproblemen unerl\u00e4sslich ist, erweist sich die Wiederverwendung von Grauwasser als innovative und nachhaltige L\u00f6sung. Was versteht man unter Grauwasser? Grauwasser stammt aus Waschbecken, Duschen und Bidets und zeichnet sich dadurch aus, dass es im Vergleich zu Schwarzwasser, das aus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":53674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[465],"tags":[],"class_list":["post-53671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten-de"],"_links":{"self":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/posts\/53671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/comments?post=53671"}],"version-history":[{"count":2,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/posts\/53671\/revisions"}],"predecessor-version":[{"id":77168,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/posts\/53671\/revisions\/77168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/media\/53674"}],"wp:attachment":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/media?parent=53671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/categories?post=53671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/tags?post=53671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}