{"id":55271,"date":"2023-04-21T09:29:36","date_gmt":"2023-04-21T09:29:36","guid":{"rendered":"https:\/\/azud.com\/casos-de-exito\/deretil-schuetzt-sich-selbst-vor-einer-algenbluete\/"},"modified":"2026-07-07T11:53:53","modified_gmt":"2026-07-07T11:53:53","slug":"deretil-schuetzt-sich-selbst-vor-einer-algenbluete","status":"publish","type":"caso-de-exito","link":"https:\/\/azud.com\/de\/erfolgsgeschichten\/deretil-schuetzt-sich-selbst-vor-einer-algenbluete\/","title":{"rendered":"Deretil sch\u00fctzt vor Algenbl\u00fcten."},"featured_media":54824,"menu_order":0,"template":"","meta":{"compania_titulo_":"DERETIL","compania_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/10\/Referencias-Deretil-1.webp","compania_texto":"<ul>\n<li><strong>Land<\/strong>: Spanien<\/li>\n<li><strong>Branche<\/strong>: Chemische Industrie<\/li>\n<li><strong>Endnutzer<\/strong>: DERETIL<\/li>\n<li><strong>Anwendung<\/strong>: Schutz von Filtermedien<\/li>\n<li><strong>Produkt<\/strong>: AZUD HELIX AUTOMATIC FT200 AA DLP INDUSTRIAL-WEHR<\/li>\n<li><strong>Durchfluss (m<sup>3<\/sup>\/h)<\/strong>: 100<\/li>\n<\/ul>\n","el_reto_imagen":"","compania_texto_copy":"","la_solucion_imagen":"https:\/\/azud.com\/wp-content\/uploads\/2025\/10\/Referencias-Deretil-1.webp","la_solucion_texto":"<p>Deretil gew\u00e4hrleistet durch den Schutz der Sandbetten einen unterbrechungsfreien Betrieb seiner Entsalzungsanlage auch bei Gezeitenwechseln.<\/p>\n","beneficios_imagen":"","beneficios_texto":""},"tipo-de-industriacultivos":[805],"subsector-casos-de-exito":[923],"lineas-de-actividad-casos":[964],"soluciones-casos-de-exito":[1201],"sector-casos-de-exito":[1069],"class_list":["post-55271","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","tipo-de-industriacultivos-quimica-y-farmaceutica","subsector-casos-de-exito-chemische-und-pharmazeutische-industrie","lineas-de-actividad-casos-filtration_de","soluciones-casos-de-exito-schutz-von-filtermedien","sector-casos-de-exito-industrie"],"_links":{"self":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/caso-de-exito\/55271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"version-history":[{"count":1,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/caso-de-exito\/55271\/revisions"}],"predecessor-version":[{"id":75163,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/caso-de-exito\/55271\/revisions\/75163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/media\/54824"}],"wp:attachment":[{"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/media?parent=55271"}],"wp:term":[{"taxonomy":"tipo-de-industriacultivos","embeddable":true,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/tipo-de-industriacultivos?post=55271"},{"taxonomy":"subsector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/subsector-casos-de-exito?post=55271"},{"taxonomy":"lineas-de-actividad-casos","embeddable":true,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/lineas-de-actividad-casos?post=55271"},{"taxonomy":"soluciones-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/soluciones-casos-de-exito?post=55271"},{"taxonomy":"sector-casos-de-exito","embeddable":true,"href":"https:\/\/azud.com\/de\/wp-json\/wp\/v2\/sector-casos-de-exito?post=55271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}